{"id":6097,"date":"2020-07-14T09:51:21","date_gmt":"2020-07-14T09:51:21","guid":{"rendered":"http:\/\/anellides.com\/blog\/quina-es-limportancia-dels-oceans\/"},"modified":"2024-08-13T09:58:09","modified_gmt":"2024-08-13T09:58:09","slug":"quina-es-limportancia-dels-oceans","status":"publish","type":"post","link":"https:\/\/anellides.com\/es\/blog\/quina-es-limportancia-dels-oceans\/","title":{"rendered":"\u00bfC\u00faal es la importancia de los oc\u00e9anos?"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Conmemorando el d\u00eda internacional de los oc\u00e9anos, el d\u00eda 8 de junio, queremos mostrar la importancia que tiene esta gran masa de agua que ocupa dos terceras partes de la superficie de nuestro planeta.<\/span><\/p>\n<h3><b>\u00bfQu\u00e9 es el oc\u00e9ano?<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">El oc\u00e9ano es constituye la enorme <\/span><b>masa <\/b><span style=\"font-weight: 400;\">total de <\/span><b>agua<\/b> <b>salada<\/b><span style=\"font-weight: 400;\"> que cubre el 71% de la superficie terrestre. El termino oc\u00e9ano se refiere a toda el agua salada, mientras que el mar se refiere a una parte de este todo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">El termino oc\u00e9ano tambi\u00e9n se aplica a cada una de las cuatro grandes regiones en las que se consideraba dividido clasicamente: Oc\u00e9ano Atl\u00e1ntico, Pac\u00edfico, \u00cdndico y \u00c0rtico. Y posteriormente se a\u00f1adi\u00f3\u00a0 el quinto: el Oc\u00e9ano Austral o Ant\u00e1rtico.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">El <\/span><b>origen<\/b><span style=\"font-weight: 400;\"> del Oc\u00e9ano se remonta a hace 4,4 billones de a\u00f1os,\u00a0 y es donde se cree probable se originara la vida de manera instant\u00e1nea tras la formaci\u00f3n del primer oc\u00e9ano terrestre, en unas surgencias hidrotermales marinas semejantes a las que hay en los fondos marinos actuales. La oxigenaci\u00f3n de la atm\u00f3sfera terrestre es producto del desarrollo de la vida y de la aparici\u00f3n de la fotos\u00edntesis,\u00a0 la cual la iniciaron unos organismos primitivos denominados cianobacterias.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Los <\/span><b>oc\u00e9anos<\/b><span style=\"font-weight: 400;\"> son de gran importancia, ya que son los responsables de que la Tierra sea habitable para la humanidad. Es la <strong>fuente<\/strong> <\/span><b>de la vida<\/b><span style=\"font-weight: 400;\"> y el gran regulador del clima en nuestro planeta. Las precipitaciones, el agua potable, el clima, el tiempo, las costas, gran parte de nuestros alimentos, incluyendo el ox\u00edgeno del aire que respiramos proviene del mar son regulados por este. Adem\u00e1s historicamente el oc\u00e9ano ha sido esencial para comercio y transporte de mercanc\u00edas.<\/span><\/p>\n<h3><b>Importancia de los oc\u00e9anos para el hombre<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">El oc\u00e9ano acoge una gran biodiversidad, concretamente de 200 mil especies identificadas,\u00a0 y\u00a0 muchas\u00a0 m\u00e1s que est\u00e1n a\u00fan por descubrir, ya que el oc\u00e9ano es la parte m\u00e1s desconocida del planeta. La humanidad siempre ha tenido una relaci\u00f3n\u00a0 estrecha con la biodiversidad marina y mantenerla es de gran importancia, porque unos 3.000 milions de personas dependen directamente de ella.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Tiene un papel determinante en la <\/span><b>producci\u00f3n primaria global<\/b><span style=\"font-weight: 400;\"> y tambi\u00e9n en los <\/span><b>ciclos de nutrientes<\/b> <b>esenciales<\/b><span style=\"font-weight: 400;\"> para la vida, como el nitr\u00f3geno y el f\u00f3sforo. Tambi\u00e9n\u00a0 el oc\u00e9ano proporciona recursos de todo tipo, como hidrocarburos, energ\u00eda, minerales y alimentos.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por otro lado, es un espacio utilizado para transporte y comercio entre continentes, el 90% del comercio mundial se realiza por mar y se utiliza para la instalaci\u00f3n de infraestructuras, vertido de residuos, realizar deportes n\u00e1uticos, etc,.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">El oc\u00e9ano juega un papel muy importante en el <\/span><b>ciclo global de carbono<\/b><span style=\"font-weight: 400;\">. <\/span>A ra\u00edz del aumento de las emisiones de CO\u2082, entre otros gases de efecto invernadero, ha habido un calentamiento global del planeta. El oc\u00e9ano absorbe el CO\u2082 y en consecuencia tiende a acidificarse.<\/p>\n<p>Toda el agua del oc\u00e9ano del planeta est\u00e1 conectada y funciona como una cinta transportadora, que lleva hacia los polos el agua caliente superficial que absorbe CO\u2082 en las latitudes tropicales del oc\u00e9ano Atl\u00e1ntico. Estos grandes sistemas de circulaci\u00f3n oce\u00e1nica son claves en la captura del CO\u2082, se estima que hoy en d\u00eda el oc\u00e9ano ha absorbido el 30% del CO\u2082 producido por los humanos.<\/p>\n<p><span style=\"font-weight: 400;\">Durante su recorrido, el agua se va enfriando lentamente y tambi\u00e9n se vuelve m\u00e1s salina. Cuando llega al mar de Groenlandia, al mar de Labrador y a les costes ant\u00e1rticas del mar de Ros y del mar de Weddell, el agua densa superficial se hunde hacia las profundidades arrastrando el CO\u2082 que contiene. A continuaci\u00f3n, las aguas ricas en CO\u2082 vuelven hacia los tr\u00f3picos. Mientras se desplazan, las aguas fr\u00edas se van mezclando con las capas m\u00e1s c\u00e1lidas que tienen encima y vuelven a subir, muy poco a poco, hacia la superficie.<\/span><\/p>\n<h3><b>Acidificaci\u00f3n<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">Los oc\u00e9anos han absorbido un tercio del CO\u2082 que hemos emitido hacia la atm\u00f3sfera desde la Revoluci\u00f3n Industrial. El resultado es un <strong>aumento<\/strong> del <strong>25%<\/strong> <strong>de la acidez del oc\u00e9ano<\/strong>. Dentro del agua el CO\u2082 se transforma en \u00e1cido carb\u00f3nico y la saturaci\u00f3n en carbonato disminuye. Esto representa un problema por ejemplo para todos los animales que utilizan el carbonato marino para fabricar sus caparazones, como los moluscos, caracoles, corales y erizos de mar entre muchos otros.<\/span><\/p>\n<h3><b>Aumento de temperaturas en los oc\u00e9anos<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">El oc\u00e9ano tiene una gran capacidad para <\/span><b>absorber<\/b><span style=\"font-weight: 400;\">\u00a0 y distribuir el <\/span><b>calor atmosf\u00e9rico<\/b><span style=\"font-weight: 400;\">, desde la d\u00e9cada de los 70 del oc\u00e9ano ha absorbido m\u00e1s del 93% del exceso de calor debido a las emisiones de los gases de efecto invernadero. Esto representa 1,3 \u00b0 C de calentamiento de media de la superficie del oc\u00e9ano en los \u00faltimos cien a\u00f1os. Aunque el \u00faltimo estudio de la revista Science de 2019 indica que el oc\u00e9ano se calentar\u00e1 un 40% m\u00e1s deprisa de lo esperado y esto se traducir\u00e1 en una aceleraci\u00f3n del aumento del nivel del mar en todo el mundo. Los efectos de este calentamiento se ven reflejados en el mismo ecosistema marino, como por ejemplos que en los \u00faltimos 150 a\u00f1os la superficie de los arrecifes de corales vivos se ha reducido a la mitad.<\/span><\/p>\n<h3><span style=\"font-weight: 400;\"><br \/>\n<\/span><b>La Pesca<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">Hace miles de a\u00f1os nuestros antepasados \u200b\u200bya depend\u00edan de la pesca para alimentarse, el <strong>pescado<\/strong> es el producto natural m\u00e1s comercializado. Pero la dependencia mundial de la pesca representa la mayor amenaza para las poblaciones de peces. Muchas especies est\u00e1n sobreexplotadas, y el n\u00famero de las que se encuentran en esta situaci\u00f3n no para de crecer.<\/span><\/p>\n<h3><b>Eutrofizaci\u00f3n<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">A medida que han ido creciendo las ciudades las aguas residuales iban a parar a r\u00edos y bah\u00edas. Hoy hay plantas de tratamiento de aguas residuales, pero desde los a\u00f1os 50 y 60 ha aparecido un factor a\u00fan m\u00e1s importante, la agricultura comercial. El esti\u00e9rcol, purines de origen animal y los fertilizantes qu\u00edmicos que utilizan estas son considerables, por lo que los cultivos no los pueden absorber completamente, lo que hace que lleguen a los r\u00edos a trav\u00e9s de las aguas subterr\u00e1neas y acaben en el mar. Una vez all\u00ed, estimulan el crecimiento del plancton y las algas. Al morir, los restos de estos organismos caen al fondo, donde las consumen las bacterias, que en este proceso utilizan hasta la \u00faltima migaja de ox\u00edgeno, la llamada eutrofizaci\u00f3n o zonas muertas frente a las costas.<\/span><\/p>\n<h3><b>Contaminaci\u00f3n<\/b><\/h3>\n<p>El <strong>40%<\/strong> del oc\u00e9ano est\u00e1 afectado debido a la contaminaci\u00f3n causada por los humanos a diferencia del 3% que se encuentra bajo protecci\u00f3n.<\/p>\n<p>Existen varios tipos de contaminaci\u00f3n como podr\u00eda ser, la contaminaci\u00f3n por <strong>petr\u00f3leo<\/strong> debida a aguas residuales, fugas durante las perforaciones petroleras, transporte mar\u00edtimo, derrames y accidentes de perforaci\u00f3n, por suerte la contaminaci\u00f3n por petr\u00f3leo ha disminuido debido a una regulaci\u00f3n m\u00e1s estricta del transporte mar\u00edtimo.<\/p>\n<p>En cuanto a la <strong>contaminaci\u00f3n por pl\u00e1sticos<\/strong> hay un problema muy grande que a medida que pasan los a\u00f1os va a peor, ya que la cantidad de residuos que terminan anualmente incrementan con el tiempo. Esto ha provocado que se formen a todos los giros oce\u00e1nicos del planeta las llamadas islas de pl\u00e1stico y que inevitablemente, al igual que los productos qu\u00edmicos y los metales pesados, los pl\u00e1sticos tambi\u00e9n han entrado en la cadena tr\u00f3fica.<\/p>\n<p>Por otro lado podemos hablar de la contaminaci\u00f3n ac\u00fastica debida al transporte mar\u00edtimo, la miner\u00eda de aguas profundas, actividades militares, instalaci\u00f3n de planchas y otras estructuras de contenci\u00f3n y subtensi\u00f3n del fondo marino para puertos y plataformas, b\u00fasqueda de reservorios de petr\u00f3leo y gas con instrumentaci\u00f3n ac\u00fastica de gran alcance, y extracci\u00f3n de petr\u00f3leo y gas natural. La contaminaci\u00f3n ac\u00fastica aumenta a medida que se incrementa su uso, y afecta gran parte de especies que habitan en este, pero en especial a los mam\u00edferos marinos, ya que se comunican y desplazan mediante el sonido.<\/p>\n<p><b>El futuro de los mares y oc\u00e9anos<\/b><\/p>\n<p>El oc\u00e9ano <strong>est\u00e1 gravemente amenazado<\/strong>, la contaminaci\u00f3n, la sobreexplotaci\u00f3n pesquera, la explotaci\u00f3n minera y la falta de \u00e1reas marinas protegidas son algunos ejemplos de las graves amenazas que recaen sobre el oc\u00e9ano.<\/p>\n<p>Conservar y utilizar de forma sostenible los oc\u00e9anos y recursos marinos nos permitir\u00e1 mantener y recuperar los caladeros de pesca, conservar especies, recuperar ecosistemas y adem\u00e1s ser capaces de responder a la crisis clim\u00e1tica, a la presencia de pl\u00e1sticos y otras actividades antropog\u00e9nicas que actualmente da\u00f1an los oc\u00e9anos.<\/p>\n<p>Una buena propuesta para llevar a cabo estas mejoras es mediante una red de santuarios marinos, los cuales protejan zonas de reproducci\u00f3n, desarrollo de especies, varios ecosistemas y las especies que habitan en ellos, prohibiendo actividades humanas que perjudiquen la biodiversidad.<\/p>\n<p>Esta propuesta ha sido debatida entre los 193 estados miembros que forman la ONU (Organizaci\u00f3n de las Naciones Unidas) con el \u00abTratado Global de los Oc\u00e9anos\u00bb, un pacto que pretende proteger la biodiversidad marina mediante la protecci\u00f3n de un 30% de las aguas internacionales de los oc\u00e9anos para el a\u00f1o 2030. el resultado de este tratado para la regulaci\u00f3n de las aguas internacionales de todos los oc\u00e9anos de la Tierra estar\u00e1 redactado este a\u00f1o 2020.<\/p>\n<p>Desde An\u00e8l\u00b7lides esperamos que el tratado aprobado sea como m\u00ednimo el que defienda la creaci\u00f3n de Santuarios Marinos al 30% de las aguas internacionales que forman los oc\u00e9anos.<\/p>\n<p><span style=\"font-weight: 400;\">Referencias<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Atles del mar. Fets i dades sobre les amenaces als ecosistemes marins. Universitat de Barcelona 08\/06\/2020<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Oc\u00e9anos 07\/06\/2020<\/span><a href=\"https:\/\/es.greenpeace.org\/es\/trabajamos-en\/oceanos\/\"> <span style=\"font-weight: 400;\">https:\/\/es.greenpeace.org\/es\/trabajamos-en\/oceanos\/<\/span><\/a><\/p>\n<p><span style=\"font-weight: 400;\">Vida submarina 08\/06\/2020<\/span><a href=\"https:\/\/www.un.org\/sustainabledevelopment\/es\/oceans\/\"> <span style=\"font-weight: 400;\">https:\/\/www.un.org\/sustainabledevelopment\/es\/oceans\/<\/span><\/a><\/p>\n<p><span style=\"font-weight: 400;\">El tratado Global de los Oc\u00e9anos estar\u00e1 aprobado a finales de 2020 08\/06\/20<\/span><a href=\"https:\/\/www.energynews.es\/tratado-global-de-los-oceanos-2020\/\"> <span style=\"font-weight: 400;\">https:\/\/www.energynews.es\/tratado-global-de-los-oceanos-2020\/<\/span><\/a><\/p>\n<p><span style=\"font-weight: 400;\">\u00bfC\u00f3mo avanza el Tratado Global por los Oc\u00e9anos? 08\/06\/2020<\/span><a href=\"https:\/\/www.greenpeace.org\/mexico\/blog\/3200\/como-avanza-el-tratado-global-por-los-oceanos\/\"> <span style=\"font-weight: 400;\">https:\/\/www.greenpeace.org\/mexico\/blog\/3200\/como-avanza-el-tratado-global-por-los-oceanos\/<\/span><\/a><\/p>\n<p><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Conmemorando el d\u00eda internacional de los oc\u00e9anos, el d\u00eda 8 de junio, queremos mostrar la importancia que tiene esta gran masa de agua que ocupa  [&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":18279,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[58],"tags":[],"class_list":["post-6097","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-oceanografia-es"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Conmemorando el d\u00eda internacional de los oc\u00e9anos, el d\u00eda 8 de junio, queremos mostrar la importancia que tiene esta gran masa de agua que ocupa dos terceras partes de la superficie de nuestro planeta. \u00bfQu\u00e9 es el oc\u00e9ano? El oc\u00e9ano es constituye la enorme masa total de agua salada que cubre el 71% de la\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Ane_admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"j5Te-Y3xjWrjCLJWsYSHtofnTHGBvK1IKvzlSorRXRc\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/anellides.com\/es\/blog\/quina-es-limportancia-dels-oceans\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/blog\\\/quina-es-limportancia-dels-oceans\\\/#article\",\"name\":\"\\u00bfC\\u00faal es la importancia de los oc\\u00e9anos? | Anellides\",\"headline\":\"\\u00bfC\\u00faal es la importancia de los oc\\u00e9anos?\",\"author\":{\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/blog\\\/author\\\/ane_admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/anellides.com\\\/wp-content\\\/files\\\/ocea.jpg\",\"width\":1280,\"height\":960},\"datePublished\":\"2020-07-14T09:51:21+00:00\",\"dateModified\":\"2024-08-13T09:58:09+00:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/blog\\\/quina-es-limportancia-dels-oceans\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/blog\\\/quina-es-limportancia-dels-oceans\\\/#webpage\"},\"articleSection\":\"Oceanograf\\u00eda, Opcional, Optional\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/blog\\\/quina-es-limportancia-dels-oceans\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/anellides.com\\\/es\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/blog\\\/category\\\/oceanografia-es\\\/#listItem\",\"name\":\"Oceanograf\\u00eda\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/blog\\\/category\\\/oceanografia-es\\\/#listItem\",\"position\":2,\"name\":\"Oceanograf\\u00eda\",\"item\":\"https:\\\/\\\/anellides.com\\\/es\\\/blog\\\/category\\\/oceanografia-es\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/blog\\\/quina-es-limportancia-dels-oceans\\\/#listItem\",\"name\":\"\\u00bfC\\u00faal es la importancia de los oc\\u00e9anos?\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/blog\\\/quina-es-limportancia-dels-oceans\\\/#listItem\",\"position\":3,\"name\":\"\\u00bfC\\u00faal es la importancia de los oc\\u00e9anos?\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/blog\\\/category\\\/oceanografia-es\\\/#listItem\",\"name\":\"Oceanograf\\u00eda\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/#organization\",\"name\":\"Anellides\",\"description\":\"Serveis Ambientals Marins\",\"url\":\"https:\\\/\\\/anellides.com\\\/es\\\/\",\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/anellides\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCY_NA_fh3v8B6uvCKdBLp4A\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/blog\\\/author\\\/ane_admin\\\/#author\",\"url\":\"https:\\\/\\\/anellides.com\\\/es\\\/blog\\\/author\\\/ane_admin\\\/\",\"name\":\"Ane_admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/blog\\\/quina-es-limportancia-dels-oceans\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/128ddaa8fd25bf4339cb192ade2a01e84e20a555b66442ee33957ea7b9aaca15?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Ane_admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/blog\\\/quina-es-limportancia-dels-oceans\\\/#webpage\",\"url\":\"https:\\\/\\\/anellides.com\\\/es\\\/blog\\\/quina-es-limportancia-dels-oceans\\\/\",\"name\":\"\\u00bfC\\u00faal es la importancia de los oc\\u00e9anos? | Anellides\",\"description\":\"Conmemorando el d\\u00eda internacional de los oc\\u00e9anos, el d\\u00eda 8 de junio, queremos mostrar la importancia que tiene esta gran masa de agua que ocupa dos terceras partes de la superficie de nuestro planeta. \\u00bfQu\\u00e9 es el oc\\u00e9ano? El oc\\u00e9ano es constituye la enorme masa total de agua salada que cubre el 71% de la\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/blog\\\/quina-es-limportancia-dels-oceans\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/blog\\\/author\\\/ane_admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/blog\\\/author\\\/ane_admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/anellides.com\\\/wp-content\\\/files\\\/ocea.jpg\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/blog\\\/quina-es-limportancia-dels-oceans\\\/#mainImage\",\"width\":1280,\"height\":960},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/blog\\\/quina-es-limportancia-dels-oceans\\\/#mainImage\"},\"datePublished\":\"2020-07-14T09:51:21+00:00\",\"dateModified\":\"2024-08-13T09:58:09+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/anellides.com\\\/es\\\/\",\"name\":\"Anellides\",\"description\":\"Serveis Ambientals Marins\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"\u00bfC\u00faal es la importancia de los oc\u00e9anos? | Anellides","description":"Conmemorando el d\u00eda internacional de los oc\u00e9anos, el d\u00eda 8 de junio, queremos mostrar la importancia que tiene esta gran masa de agua que ocupa dos terceras partes de la superficie de nuestro planeta. \u00bfQu\u00e9 es el oc\u00e9ano? El oc\u00e9ano es constituye la enorme masa total de agua salada que cubre el 71% de la","canonical_url":"https:\/\/anellides.com\/es\/blog\/quina-es-limportancia-dels-oceans\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"j5Te-Y3xjWrjCLJWsYSHtofnTHGBvK1IKvzlSorRXRc","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/anellides.com\/es\/blog\/quina-es-limportancia-dels-oceans\/#article","name":"\u00bfC\u00faal es la importancia de los oc\u00e9anos? | Anellides","headline":"\u00bfC\u00faal es la importancia de los oc\u00e9anos?","author":{"@id":"https:\/\/anellides.com\/es\/blog\/author\/ane_admin\/#author"},"publisher":{"@id":"https:\/\/anellides.com\/es\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/anellides.com\/wp-content\/files\/ocea.jpg","width":1280,"height":960},"datePublished":"2020-07-14T09:51:21+00:00","dateModified":"2024-08-13T09:58:09+00:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/anellides.com\/es\/blog\/quina-es-limportancia-dels-oceans\/#webpage"},"isPartOf":{"@id":"https:\/\/anellides.com\/es\/blog\/quina-es-limportancia-dels-oceans\/#webpage"},"articleSection":"Oceanograf\u00eda, Opcional, Optional"},{"@type":"BreadcrumbList","@id":"https:\/\/anellides.com\/es\/blog\/quina-es-limportancia-dels-oceans\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/anellides.com\/es\/#listItem","position":1,"name":"Home","item":"https:\/\/anellides.com\/es\/","nextItem":{"@type":"ListItem","@id":"https:\/\/anellides.com\/es\/blog\/category\/oceanografia-es\/#listItem","name":"Oceanograf\u00eda"}},{"@type":"ListItem","@id":"https:\/\/anellides.com\/es\/blog\/category\/oceanografia-es\/#listItem","position":2,"name":"Oceanograf\u00eda","item":"https:\/\/anellides.com\/es\/blog\/category\/oceanografia-es\/","nextItem":{"@type":"ListItem","@id":"https:\/\/anellides.com\/es\/blog\/quina-es-limportancia-dels-oceans\/#listItem","name":"\u00bfC\u00faal es la importancia de los oc\u00e9anos?"},"previousItem":{"@type":"ListItem","@id":"https:\/\/anellides.com\/es\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/anellides.com\/es\/blog\/quina-es-limportancia-dels-oceans\/#listItem","position":3,"name":"\u00bfC\u00faal es la importancia de los oc\u00e9anos?","previousItem":{"@type":"ListItem","@id":"https:\/\/anellides.com\/es\/blog\/category\/oceanografia-es\/#listItem","name":"Oceanograf\u00eda"}}]},{"@type":"Organization","@id":"https:\/\/anellides.com\/es\/#organization","name":"Anellides","description":"Serveis Ambientals Marins","url":"https:\/\/anellides.com\/es\/","sameAs":["https:\/\/www.instagram.com\/anellides\/","https:\/\/www.youtube.com\/channel\/UCY_NA_fh3v8B6uvCKdBLp4A"]},{"@type":"Person","@id":"https:\/\/anellides.com\/es\/blog\/author\/ane_admin\/#author","url":"https:\/\/anellides.com\/es\/blog\/author\/ane_admin\/","name":"Ane_admin","image":{"@type":"ImageObject","@id":"https:\/\/anellides.com\/es\/blog\/quina-es-limportancia-dels-oceans\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/128ddaa8fd25bf4339cb192ade2a01e84e20a555b66442ee33957ea7b9aaca15?s=96&d=mm&r=g","width":96,"height":96,"caption":"Ane_admin"}},{"@type":"WebPage","@id":"https:\/\/anellides.com\/es\/blog\/quina-es-limportancia-dels-oceans\/#webpage","url":"https:\/\/anellides.com\/es\/blog\/quina-es-limportancia-dels-oceans\/","name":"\u00bfC\u00faal es la importancia de los oc\u00e9anos? | Anellides","description":"Conmemorando el d\u00eda internacional de los oc\u00e9anos, el d\u00eda 8 de junio, queremos mostrar la importancia que tiene esta gran masa de agua que ocupa dos terceras partes de la superficie de nuestro planeta. \u00bfQu\u00e9 es el oc\u00e9ano? El oc\u00e9ano es constituye la enorme masa total de agua salada que cubre el 71% de la","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/anellides.com\/es\/#website"},"breadcrumb":{"@id":"https:\/\/anellides.com\/es\/blog\/quina-es-limportancia-dels-oceans\/#breadcrumblist"},"author":{"@id":"https:\/\/anellides.com\/es\/blog\/author\/ane_admin\/#author"},"creator":{"@id":"https:\/\/anellides.com\/es\/blog\/author\/ane_admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/anellides.com\/wp-content\/files\/ocea.jpg","@id":"https:\/\/anellides.com\/es\/blog\/quina-es-limportancia-dels-oceans\/#mainImage","width":1280,"height":960},"primaryImageOfPage":{"@id":"https:\/\/anellides.com\/es\/blog\/quina-es-limportancia-dels-oceans\/#mainImage"},"datePublished":"2020-07-14T09:51:21+00:00","dateModified":"2024-08-13T09:58:09+00:00"},{"@type":"WebSite","@id":"https:\/\/anellides.com\/es\/#website","url":"https:\/\/anellides.com\/es\/","name":"Anellides","description":"Serveis Ambientals Marins","inLanguage":"es-ES","publisher":{"@id":"https:\/\/anellides.com\/es\/#organization"}}]}},"aioseo_meta_data":{"post_id":"6097","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-03-25 18:21:06","updated":"2025-06-04 12:29:15","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/anellides.com\/es\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/anellides.com\/es\/blog\/category\/oceanografia-es\/\" title=\"Oceanograf\u00eda\">Oceanograf\u00eda<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t\u00bfC\u00faal es la importancia de los oc\u00e9anos?\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/anellides.com\/es\/"},{"label":"Oceanograf\u00eda","link":"https:\/\/anellides.com\/es\/blog\/category\/oceanografia-es\/"},{"label":"\u00bfC\u00faal es la importancia de los oc\u00e9anos?","link":"https:\/\/anellides.com\/es\/blog\/quina-es-limportancia-dels-oceans\/"}],"_links":{"self":[{"href":"https:\/\/anellides.com\/es\/wp-json\/wp\/v2\/posts\/6097","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/anellides.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/anellides.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/anellides.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/anellides.com\/es\/wp-json\/wp\/v2\/comments?post=6097"}],"version-history":[{"count":2,"href":"https:\/\/anellides.com\/es\/wp-json\/wp\/v2\/posts\/6097\/revisions"}],"predecessor-version":[{"id":6348,"href":"https:\/\/anellides.com\/es\/wp-json\/wp\/v2\/posts\/6097\/revisions\/6348"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/anellides.com\/es\/wp-json\/wp\/v2\/media\/18279"}],"wp:attachment":[{"href":"https:\/\/anellides.com\/es\/wp-json\/wp\/v2\/media?parent=6097"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/anellides.com\/es\/wp-json\/wp\/v2\/categories?post=6097"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/anellides.com\/es\/wp-json\/wp\/v2\/tags?post=6097"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}