{"id":6098,"date":"2020-07-14T10:10:05","date_gmt":"2020-07-14T10:10:05","guid":{"rendered":"http:\/\/anellides.com\/blog\/reciclar-ayuda-a-contrarrestar-la-contaminacion\/"},"modified":"2024-08-13T10:00:08","modified_gmt":"2024-08-13T10:00:08","slug":"reciclar-ayuda-a-contrarrestar-la-contaminacion","status":"publish","type":"post","link":"https:\/\/anellides.com\/es\/blog\/reciclar-ayuda-a-contrarrestar-la-contaminacion\/","title":{"rendered":"Reciclar ayuda a contrarrestar la contaminaci\u00f3n"},"content":{"rendered":"<ul>\n<li><b>Por cada 6 latas <\/b><span style=\"font-weight: 400;\">o botellas de pl\u00e1stico que reciclamos <\/span><b>contrarrestamos la contaminaci\u00f3n de 10 minutos del tubo de escape<\/b><span style=\"font-weight: 400;\"> de un veh\u00edculo (1)<\/span><span style=\"font-weight: 400;\">El pasado 17 de mayo fue el d\u00eda<\/span><b> Mundial del reciclaje,<\/b><span style=\"font-weight: 400;\"> celebrado desde 2005, para concienciar a la poblaci\u00f3n de la importancia del tratamiento de residuos para la protecci\u00f3n del medio ambiente. En conmemoraci\u00f3n queremos dedicar la siguiente entrada a explicar la import\u00e0ncia del reciclaje y mostrar los impactos que produce y c\u00f3mo ser m\u00e1s sostenibles.<\/span>\n<p><b>Reciclamos, m\u00e1s y mejor<\/b><\/p>\n<p><span style=\"font-weight: 400;\">El reciclaje comienza en cada casa, separando los envases y depositarlos en los correctos en los contenedores . Pero c\u00f3mo sabemos si lo estamos haciendo bien? Todos tienen muchas dudas al respecto<\/span><\/p>\n<p><b>Todo envase al amarillo<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Los envases met\u00e1licos, los envases de pl\u00e1sticos y los tetra-bricks al amarillo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00bfQu\u00e9 entendemos por <\/span><b>envases met\u00e1licos<\/b><span style=\"font-weight: 400;\">? Latas de bebidas y de conservas, bandejas de aluminio, aerosoles y tapones de metal de cualquier bote o botella. \u00bfY por los<\/span><b> envases de pl\u00e1stico<\/b><span style=\"font-weight: 400;\">? Botellas de agua, refrescos y leches, de productos de limpieza, geles de ba\u00f1o, colonias y champ\u00fas; bolsas de congelados; tarrinas de mantequilla y yogures; bandejas de porexpan, envoltorios de pl\u00e1stico, bolsas de aperitivos y golosinas y las bolsas de pl\u00e1stico.<\/span><\/p>\n<p><b>El azul es igual a cart\u00f3n<\/b><\/p>\n<p><span style=\"font-weight: 400;\">En el contenedor azul se deben tirar cart\u00f3n, as\u00ed como todo tipo de papel.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Los cartones m\u00e1s frecuentes suelen ser de cajas de galletas, de cereales, de productos congelados, cajas de zapatos, hueveras de cart\u00f3n, etc. En cuanto al papel en general, los m\u00e1s frecuentes son los peri\u00f3dicos, libros, revistas y bolsas de papel (es interesante reutilizar las bolsas de papel para meter los cartones y llevarlo todo junto al contenedor azul, ya que as\u00ed se le da otro uso a la bolsa).<\/span><\/p>\n<p><b>El verde, \u00bfVidrio d\u00f3nde est\u00e1s?<\/b><\/p>\n<p><span style=\"font-weight: 400;\">En el contenedor verde se puede depositar cualquier botella de <\/span><b>vidrio<\/b><span style=\"font-weight: 400;\">, los botes de cosm\u00e9tica y de colonia y tambi\u00e9n los botes de mermeladas y conservas. Hay que recordar que para facilitar el reciclaje de estos productos, se debe quitar el tap\u00f3n de los envases (el cual al amarillo) antes de tirarlos al contenedor verde.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Cabe mencionar,, que hay bastantes productos que nos pueden llevar a una confusi\u00f3n, ya que parece que se tengan que tirar al contenedor verde, y no es as\u00ed. Los m\u00e1s frecuentes son las bombillas, los tubos fluorescentes, la porcelana, la cer\u00e1mica, el vidrio de ventanas o espejos, vasos y copas de cristal.<\/span><\/p>\n<p><b>El org\u00e1nico, es el marr\u00f3n<\/b><\/p>\n<p><span style=\"font-weight: 400;\">En el contenedor marr\u00f3n van los residuos <\/span><b>biodegradables <\/b><span style=\"font-weight: 400;\">y los desechos org\u00e1nicos.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Se entiende por <\/span><b>residuos biodegradables<\/b><span style=\"font-weight: 400;\"> conchas y c\u00e1scaras de fruta, restos de carne, pescado y verdura, caf\u00e9, restos de infusiones, etc. En cuanto a los desechos org\u00e1nicos, nos referimos a papeles y cartones manchados de grasa o aceite, peque\u00f1os restos vegetales de flores y hojas tapones de corcho y serr\u00edn.<\/span><\/p>\n<p><b>El resto al gris<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Todos el<\/span><b> resto de residuos <\/b><span style=\"font-weight: 400;\">que no sean envases y que no tengan ning\u00fan sistema especial de recogida deber\u00e1n tirar al rechazo o resto, el contenedor gris. Los art\u00edculos m\u00e1s frecuentes que se tiran a esta fracci\u00f3n son los pa\u00f1ales, sartenes viejas, restos de vajillas o cubiertos, juguetes estropeadas o rotas, espejos rotos, objetos de pl\u00e1stico o metal que no sean envases, etc.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En el estado de alarma que estamos viviendo actualmente, queremos transmitir nuestra preocupaci\u00f3n en el elevado n\u00famero de residuos desechables generados. Todos estos residuos<\/span><b> mascarillas <\/b><span style=\"font-weight: 400;\">y <\/span><b>guantes<\/b><span style=\"font-weight: 400;\"> desechables se deben tirar en el contenedor gris. Pero hay que ser conscientes de reutilizarlos al m\u00e1ximo posible, buscar alternativas de objetos <\/span><b>m\u00e1s sostenibles<\/b><span style=\"font-weight: 400;\"> y tener presente que el mejor residuo es el que no se genera.<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Por \u00faltimo, nos gustar\u00eda dar algunos consejos para conseguir un correcto reciclaje (2):<\/span>\n<p><span style=\"font-weight: 400;\">Es interesante comprar productos que sean respetuosos con el medio ambiente.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Haz del reciclaje un juego. Los m\u00e1s peque\u00f1os pueden aprender a reciclar divirti\u00e9ndose.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Reutiliza las bolsas de pl\u00e1stico tantas veces como sea posible, y al final de su uso, utilizarlas para meter envases de pl\u00e1stico y tira en el contenedor amarillo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Para que el reciclaje sea m\u00e1s efectivo, vac\u00eda los envases antes de llevarlos al contenedor.<\/span><\/li>\n<\/ul>\n<p><strong>Refer\u00e8ncies<\/strong><\/p>\n<p>(1) Guia para reciclar m\u00e1s y mejor. Ecoembes. El poder de la col\u00b7laboraci\u00f3n. file:\/\/\/C:\/Users\/pc\/Downloads\/guia-amb-contenidor-recollida-selectiva-materia-organica.pdf<\/p>\n<p>(2) 10 consejos para reciclar de forma correcta <a href=\"https:\/\/www.diarioinformacion.com\/empresas-en-alicante\/2018\/05\/17\/10-consejos-reciclar-forma-correcta\/2021549.html\">https:\/\/www.diarioinformacion.com\/empresas-en-alicante\/2018\/05\/17\/10-consejos-reciclar-forma-correcta\/2021549.html<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por cada 6 latas o botellas de pl\u00e1stico que reciclamos contrarrestamos la contaminaci\u00f3n de 10 minutos del tubo de escape de un veh\u00edculo (1)El pasado  [&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":18476,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[59],"tags":[61,60],"class_list":["post-6098","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacion-ambiental","tag-problematiques-ambientals-es","tag-sensibilitzacion-ambiental"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Por cada 6 latas o botellas de pl\u00e1stico que reciclamos contrarrestamos la contaminaci\u00f3n de 10 minutos del tubo de escape de un veh\u00edculo (1)El pasado 17 de mayo fue el d\u00eda Mundial del reciclaje, celebrado desde 2005, para concienciar a la poblaci\u00f3n de la importancia del tratamiento de residuos para la protecci\u00f3n del medio ambiente.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Ane_admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"j5Te-Y3xjWrjCLJWsYSHtofnTHGBvK1IKvzlSorRXRc\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/anellides.com\/es\/blog\/reciclar-ayuda-a-contrarrestar-la-contaminacion\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/blog\\\/reciclar-ayuda-a-contrarrestar-la-contaminacion\\\/#article\",\"name\":\"Reciclar ayuda a contrarrestar la contaminaci\\u00f3n | Anellides\",\"headline\":\"Reciclar ayuda a contrarrestar la contaminaci\\u00f3n\",\"author\":{\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/blog\\\/author\\\/ane_admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/anellides.com\\\/wp-content\\\/files\\\/reci.jpg\",\"width\":1280,\"height\":1280},\"datePublished\":\"2020-07-14T10:10:05+00:00\",\"dateModified\":\"2024-08-13T10:00:08+00:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/blog\\\/reciclar-ayuda-a-contrarrestar-la-contaminacion\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/blog\\\/reciclar-ayuda-a-contrarrestar-la-contaminacion\\\/#webpage\"},\"articleSection\":\"Educaci\\u00f3n ambiental, Problem\\u00e1tiques ambientals, Sensibilitzaci\\u00f3n ambiental, Opcional, Optional\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/blog\\\/reciclar-ayuda-a-contrarrestar-la-contaminacion\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/anellides.com\\\/es\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/blog\\\/category\\\/educacion-ambiental\\\/#listItem\",\"name\":\"Educaci\\u00f3n ambiental\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/blog\\\/category\\\/educacion-ambiental\\\/#listItem\",\"position\":2,\"name\":\"Educaci\\u00f3n ambiental\",\"item\":\"https:\\\/\\\/anellides.com\\\/es\\\/blog\\\/category\\\/educacion-ambiental\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/blog\\\/reciclar-ayuda-a-contrarrestar-la-contaminacion\\\/#listItem\",\"name\":\"Reciclar ayuda a contrarrestar la contaminaci\\u00f3n\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/blog\\\/reciclar-ayuda-a-contrarrestar-la-contaminacion\\\/#listItem\",\"position\":3,\"name\":\"Reciclar ayuda a contrarrestar la contaminaci\\u00f3n\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/blog\\\/category\\\/educacion-ambiental\\\/#listItem\",\"name\":\"Educaci\\u00f3n ambiental\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/#organization\",\"name\":\"Anellides\",\"description\":\"Serveis Ambientals Marins\",\"url\":\"https:\\\/\\\/anellides.com\\\/es\\\/\",\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/anellides\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCY_NA_fh3v8B6uvCKdBLp4A\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/blog\\\/author\\\/ane_admin\\\/#author\",\"url\":\"https:\\\/\\\/anellides.com\\\/es\\\/blog\\\/author\\\/ane_admin\\\/\",\"name\":\"Ane_admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/blog\\\/reciclar-ayuda-a-contrarrestar-la-contaminacion\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/128ddaa8fd25bf4339cb192ade2a01e84e20a555b66442ee33957ea7b9aaca15?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Ane_admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/blog\\\/reciclar-ayuda-a-contrarrestar-la-contaminacion\\\/#webpage\",\"url\":\"https:\\\/\\\/anellides.com\\\/es\\\/blog\\\/reciclar-ayuda-a-contrarrestar-la-contaminacion\\\/\",\"name\":\"Reciclar ayuda a contrarrestar la contaminaci\\u00f3n | Anellides\",\"description\":\"Por cada 6 latas o botellas de pl\\u00e1stico que reciclamos contrarrestamos la contaminaci\\u00f3n de 10 minutos del tubo de escape de un veh\\u00edculo (1)El pasado 17 de mayo fue el d\\u00eda Mundial del reciclaje, celebrado desde 2005, para concienciar a la poblaci\\u00f3n de la importancia del tratamiento de residuos para la protecci\\u00f3n del medio ambiente.\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/blog\\\/reciclar-ayuda-a-contrarrestar-la-contaminacion\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/blog\\\/author\\\/ane_admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/blog\\\/author\\\/ane_admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/anellides.com\\\/wp-content\\\/files\\\/reci.jpg\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/blog\\\/reciclar-ayuda-a-contrarrestar-la-contaminacion\\\/#mainImage\",\"width\":1280,\"height\":1280},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/blog\\\/reciclar-ayuda-a-contrarrestar-la-contaminacion\\\/#mainImage\"},\"datePublished\":\"2020-07-14T10:10:05+00:00\",\"dateModified\":\"2024-08-13T10:00:08+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/anellides.com\\\/es\\\/\",\"name\":\"Anellides\",\"description\":\"Serveis Ambientals Marins\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Reciclar ayuda a contrarrestar la contaminaci\u00f3n | Anellides","description":"Por cada 6 latas o botellas de pl\u00e1stico que reciclamos contrarrestamos la contaminaci\u00f3n de 10 minutos del tubo de escape de un veh\u00edculo (1)El pasado 17 de mayo fue el d\u00eda Mundial del reciclaje, celebrado desde 2005, para concienciar a la poblaci\u00f3n de la importancia del tratamiento de residuos para la protecci\u00f3n del medio ambiente.","canonical_url":"https:\/\/anellides.com\/es\/blog\/reciclar-ayuda-a-contrarrestar-la-contaminacion\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"j5Te-Y3xjWrjCLJWsYSHtofnTHGBvK1IKvzlSorRXRc","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/anellides.com\/es\/blog\/reciclar-ayuda-a-contrarrestar-la-contaminacion\/#article","name":"Reciclar ayuda a contrarrestar la contaminaci\u00f3n | Anellides","headline":"Reciclar ayuda a contrarrestar la contaminaci\u00f3n","author":{"@id":"https:\/\/anellides.com\/es\/blog\/author\/ane_admin\/#author"},"publisher":{"@id":"https:\/\/anellides.com\/es\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/anellides.com\/wp-content\/files\/reci.jpg","width":1280,"height":1280},"datePublished":"2020-07-14T10:10:05+00:00","dateModified":"2024-08-13T10:00:08+00:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/anellides.com\/es\/blog\/reciclar-ayuda-a-contrarrestar-la-contaminacion\/#webpage"},"isPartOf":{"@id":"https:\/\/anellides.com\/es\/blog\/reciclar-ayuda-a-contrarrestar-la-contaminacion\/#webpage"},"articleSection":"Educaci\u00f3n ambiental, Problem\u00e1tiques ambientals, Sensibilitzaci\u00f3n ambiental, Opcional, Optional"},{"@type":"BreadcrumbList","@id":"https:\/\/anellides.com\/es\/blog\/reciclar-ayuda-a-contrarrestar-la-contaminacion\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/anellides.com\/es\/#listItem","position":1,"name":"Home","item":"https:\/\/anellides.com\/es\/","nextItem":{"@type":"ListItem","@id":"https:\/\/anellides.com\/es\/blog\/category\/educacion-ambiental\/#listItem","name":"Educaci\u00f3n ambiental"}},{"@type":"ListItem","@id":"https:\/\/anellides.com\/es\/blog\/category\/educacion-ambiental\/#listItem","position":2,"name":"Educaci\u00f3n ambiental","item":"https:\/\/anellides.com\/es\/blog\/category\/educacion-ambiental\/","nextItem":{"@type":"ListItem","@id":"https:\/\/anellides.com\/es\/blog\/reciclar-ayuda-a-contrarrestar-la-contaminacion\/#listItem","name":"Reciclar ayuda a contrarrestar la contaminaci\u00f3n"},"previousItem":{"@type":"ListItem","@id":"https:\/\/anellides.com\/es\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/anellides.com\/es\/blog\/reciclar-ayuda-a-contrarrestar-la-contaminacion\/#listItem","position":3,"name":"Reciclar ayuda a contrarrestar la contaminaci\u00f3n","previousItem":{"@type":"ListItem","@id":"https:\/\/anellides.com\/es\/blog\/category\/educacion-ambiental\/#listItem","name":"Educaci\u00f3n ambiental"}}]},{"@type":"Organization","@id":"https:\/\/anellides.com\/es\/#organization","name":"Anellides","description":"Serveis Ambientals Marins","url":"https:\/\/anellides.com\/es\/","sameAs":["https:\/\/www.instagram.com\/anellides\/","https:\/\/www.youtube.com\/channel\/UCY_NA_fh3v8B6uvCKdBLp4A"]},{"@type":"Person","@id":"https:\/\/anellides.com\/es\/blog\/author\/ane_admin\/#author","url":"https:\/\/anellides.com\/es\/blog\/author\/ane_admin\/","name":"Ane_admin","image":{"@type":"ImageObject","@id":"https:\/\/anellides.com\/es\/blog\/reciclar-ayuda-a-contrarrestar-la-contaminacion\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/128ddaa8fd25bf4339cb192ade2a01e84e20a555b66442ee33957ea7b9aaca15?s=96&d=mm&r=g","width":96,"height":96,"caption":"Ane_admin"}},{"@type":"WebPage","@id":"https:\/\/anellides.com\/es\/blog\/reciclar-ayuda-a-contrarrestar-la-contaminacion\/#webpage","url":"https:\/\/anellides.com\/es\/blog\/reciclar-ayuda-a-contrarrestar-la-contaminacion\/","name":"Reciclar ayuda a contrarrestar la contaminaci\u00f3n | Anellides","description":"Por cada 6 latas o botellas de pl\u00e1stico que reciclamos contrarrestamos la contaminaci\u00f3n de 10 minutos del tubo de escape de un veh\u00edculo (1)El pasado 17 de mayo fue el d\u00eda Mundial del reciclaje, celebrado desde 2005, para concienciar a la poblaci\u00f3n de la importancia del tratamiento de residuos para la protecci\u00f3n del medio ambiente.","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/anellides.com\/es\/#website"},"breadcrumb":{"@id":"https:\/\/anellides.com\/es\/blog\/reciclar-ayuda-a-contrarrestar-la-contaminacion\/#breadcrumblist"},"author":{"@id":"https:\/\/anellides.com\/es\/blog\/author\/ane_admin\/#author"},"creator":{"@id":"https:\/\/anellides.com\/es\/blog\/author\/ane_admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/anellides.com\/wp-content\/files\/reci.jpg","@id":"https:\/\/anellides.com\/es\/blog\/reciclar-ayuda-a-contrarrestar-la-contaminacion\/#mainImage","width":1280,"height":1280},"primaryImageOfPage":{"@id":"https:\/\/anellides.com\/es\/blog\/reciclar-ayuda-a-contrarrestar-la-contaminacion\/#mainImage"},"datePublished":"2020-07-14T10:10:05+00:00","dateModified":"2024-08-13T10:00:08+00:00"},{"@type":"WebSite","@id":"https:\/\/anellides.com\/es\/#website","url":"https:\/\/anellides.com\/es\/","name":"Anellides","description":"Serveis Ambientals Marins","inLanguage":"es-ES","publisher":{"@id":"https:\/\/anellides.com\/es\/#organization"}}]}},"aioseo_meta_data":{"post_id":"6098","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-03-25 18:21:06","updated":"2025-06-04 12:29:15","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/anellides.com\/es\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/anellides.com\/es\/blog\/category\/educacion-ambiental\/\" title=\"Educaci\u00f3n ambiental\">Educaci\u00f3n ambiental<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tReciclar ayuda a contrarrestar la contaminaci\u00f3n\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/anellides.com\/es\/"},{"label":"Educaci\u00f3n ambiental","link":"https:\/\/anellides.com\/es\/blog\/category\/educacion-ambiental\/"},{"label":"Reciclar ayuda a contrarrestar la contaminaci\u00f3n","link":"https:\/\/anellides.com\/es\/blog\/reciclar-ayuda-a-contrarrestar-la-contaminacion\/"}],"_links":{"self":[{"href":"https:\/\/anellides.com\/es\/wp-json\/wp\/v2\/posts\/6098","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/anellides.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/anellides.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/anellides.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/anellides.com\/es\/wp-json\/wp\/v2\/comments?post=6098"}],"version-history":[{"count":1,"href":"https:\/\/anellides.com\/es\/wp-json\/wp\/v2\/posts\/6098\/revisions"}],"predecessor-version":[{"id":18482,"href":"https:\/\/anellides.com\/es\/wp-json\/wp\/v2\/posts\/6098\/revisions\/18482"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/anellides.com\/es\/wp-json\/wp\/v2\/media\/18476"}],"wp:attachment":[{"href":"https:\/\/anellides.com\/es\/wp-json\/wp\/v2\/media?parent=6098"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/anellides.com\/es\/wp-json\/wp\/v2\/categories?post=6098"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/anellides.com\/es\/wp-json\/wp\/v2\/tags?post=6098"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}