{"id":6206,"date":"2020-07-17T11:14:29","date_gmt":"2020-07-17T11:14:29","guid":{"rendered":"http:\/\/anellides.com\/blog\/como-son-las-tortugas-marinas-parte-1\/"},"modified":"2024-08-13T10:10:57","modified_gmt":"2024-08-13T10:10:57","slug":"como-son-las-tortugas-marinas-parte-1","status":"publish","type":"post","link":"https:\/\/anellides.com\/es\/blog\/como-son-las-tortugas-marinas-parte-1\/","title":{"rendered":"\u00bfC\u00f3mo son las tortugas marinas? (parte 1)"},"content":{"rendered":"<p>Esta entrada pretende resumir los rasgos caracter\u00edsticos generales de las siete especies de tortugas marinas que hoy en d\u00eda habitan los mares y oc\u00e9anos del planeta tierra, as\u00ed como los rasgos morfol\u00f3gicos, anat\u00f3micos y adaptaciones fisiol\u00f3gicas de estas.<\/p>\n<h3>Diferencias entre tortugas terrestres y tortugas marinas<\/h3>\n<p>Las tortugas marinas, de agua dulce y terrestre presentan morfolog\u00edas diferentes debido a la adaptaci\u00f3n que han sufrido por vivir en medios tan diferentes. A continuaci\u00f3n se exponen diferencias morfol\u00f3gicas entre diversas tortugas.<\/p>\n<p style=\"text-align: center;\">\u00a0<img decoding=\"async\" class=\"alignnone  wp-image-18487\" src=\"https:\/\/anellides.com\/wp-content\/files\/TOR.jpg\" alt=\"\" width=\"314\" height=\"190\" srcset=\"\/\/anellides.com\/wp-content\/files\/TOR-66x40.jpg 66w, \/\/anellides.com\/wp-content\/files\/TOR-177x107.jpg 177w, \/\/anellides.com\/wp-content\/files\/TOR-200x121.jpg 200w, \/\/anellides.com\/wp-content\/files\/TOR-300x181.jpg 300w, \/\/anellides.com\/wp-content\/files\/TOR-320x193.jpg 320w, \/\/anellides.com\/wp-content\/files\/TOR-400x242.jpg 400w, \/\/anellides.com\/wp-content\/files\/TOR-460x278.jpg 460w, \/\/anellides.com\/wp-content\/files\/TOR-500x302.jpg 500w, \/\/anellides.com\/wp-content\/files\/TOR-540x326.jpg 540w, \/\/anellides.com\/wp-content\/files\/TOR-600x363.jpg 600w, \/\/anellides.com\/wp-content\/files\/TOR-669x404.jpg 669w, \/\/anellides.com\/wp-content\/files\/TOR-700x423.jpg 700w, \/\/anellides.com\/wp-content\/files\/TOR-800x483.jpg 800w, \/\/anellides.com\/wp-content\/files\/TOR-940x568.jpg 940w, \/\/anellides.com\/wp-content\/files\/TOR.jpg 960w\" sizes=\"(max-width: 314px) 100vw, 314px\" \/> <img decoding=\"async\" class=\"alignnone wp-image-18490 \" src=\"https:\/\/anellides.com\/wp-content\/files\/TORT2-e1723543517820.jpg\" alt=\"\" width=\"280\" height=\"190\" srcset=\"\/\/anellides.com\/wp-content\/files\/TORT2-e1723543517820-66x45.jpg 66w, \/\/anellides.com\/wp-content\/files\/TORT2-e1723543517820-177x120.jpg 177w, \/\/anellides.com\/wp-content\/files\/TORT2-e1723543517820-200x136.jpg 200w, \/\/anellides.com\/wp-content\/files\/TORT2-e1723543517820-300x204.jpg 300w, \/\/anellides.com\/wp-content\/files\/TORT2-e1723543517820-320x217.jpg 320w, \/\/anellides.com\/wp-content\/files\/TORT2-e1723543517820-400x272.jpg 400w, \/\/anellides.com\/wp-content\/files\/TORT2-e1723543517820-460x313.jpg 460w, \/\/anellides.com\/wp-content\/files\/TORT2-e1723543517820-500x340.jpg 500w, \/\/anellides.com\/wp-content\/files\/TORT2-e1723543517820-540x367.jpg 540w, \/\/anellides.com\/wp-content\/files\/TORT2-e1723543517820-600x408.jpg 600w, \/\/anellides.com\/wp-content\/files\/TORT2-e1723543517820-669x455.jpg 669w, \/\/anellides.com\/wp-content\/files\/TORT2-e1723543517820.jpg 674w\" sizes=\"(max-width: 280px) 100vw, 280px\" \/> <img decoding=\"async\" class=\"alignnone  wp-image-18484\" src=\"https:\/\/anellides.com\/wp-content\/files\/TPRT3.jpg\" alt=\"\" width=\"287\" height=\"191\" srcset=\"\/\/anellides.com\/wp-content\/files\/TPRT3-66x44.jpg 66w, \/\/anellides.com\/wp-content\/files\/TPRT3-177x118.jpg 177w, \/\/anellides.com\/wp-content\/files\/TPRT3-200x133.jpg 200w, \/\/anellides.com\/wp-content\/files\/TPRT3-300x200.jpg 300w, \/\/anellides.com\/wp-content\/files\/TPRT3-320x214.jpg 320w, \/\/anellides.com\/wp-content\/files\/TPRT3-400x267.jpg 400w, \/\/anellides.com\/wp-content\/files\/TPRT3-460x307.jpg 460w, \/\/anellides.com\/wp-content\/files\/TPRT3-500x334.jpg 500w, \/\/anellides.com\/wp-content\/files\/TPRT3-540x360.jpg 540w, \/\/anellides.com\/wp-content\/files\/TPRT3-600x400.jpg 600w, \/\/anellides.com\/wp-content\/files\/TPRT3-669x446.jpg 669w, \/\/anellides.com\/wp-content\/files\/TPRT3-700x467.jpg 700w, \/\/anellides.com\/wp-content\/files\/TPRT3-800x534.jpg 800w, \/\/anellides.com\/wp-content\/files\/TPRT3-940x627.jpg 940w, \/\/anellides.com\/wp-content\/files\/TPRT3-1024x683.jpg 1024w, \/\/anellides.com\/wp-content\/files\/TPRT3-1200x801.jpg 1200w, \/\/anellides.com\/wp-content\/files\/TPRT3.jpg 1280w\" sizes=\"(max-width: 287px) 100vw, 287px\" \/><br \/>\n<strong><em>Testudo hermanni\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 C<\/em><\/strong><strong><em>helonia mydas\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Trachemys sp<\/em><\/strong><\/p>\n<p style=\"text-align: center;\"><strong>Tortuga terrestre\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 Tortuga marina\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Tortuga de agua dulce<\/strong><\/p>\n<p><strong><img decoding=\"async\" class=\" wp-image-5092 aligncenter\" src=\"https:\/\/anellides.com\/wp-content\/files\/taula-diferencies-tortugues.png\" alt=\"taula-diferencies-tortugues\" width=\"702\" height=\"334\" srcset=\"\/\/anellides.com\/wp-content\/files\/taula-diferencies-tortugues-200x95.png 200w, \/\/anellides.com\/wp-content\/files\/taula-diferencies-tortugues-300x143.png 300w, \/\/anellides.com\/wp-content\/files\/taula-diferencies-tortugues-400x190.png 400w, \/\/anellides.com\/wp-content\/files\/taula-diferencies-tortugues-500x238.png 500w, \/\/anellides.com\/wp-content\/files\/taula-diferencies-tortugues-600x285.png 600w, \/\/anellides.com\/wp-content\/files\/taula-diferencies-tortugues-700x333.png 700w, \/\/anellides.com\/wp-content\/files\/taula-diferencies-tortugues-800x380.png 800w, \/\/anellides.com\/wp-content\/files\/taula-diferencies-tortugues.png 959w\" sizes=\"(max-width: 702px) 100vw, 702px\" \/>\u00a0<\/strong><strong>\u00a0<\/strong><\/p>\n<h3>Especies de tortugas marinas<\/h3>\n<p>Actualmente existen siete especies de tortugas distribuidas por los mares y oc\u00e9anos del mundo. Las tortugas marinas forman parte de la superfamilia de tortugas <em>quelonioideos (Chelonioidea)<\/em>. Estas est\u00e1n distribuidas en dos familias:\u00a0<em>Cheloniidae<\/em>, caracterizada pro presentar una concha osea y placas d\u00e9rmicas y\u00a0<em>Demochelydae<\/em>, la cual incluye a una sola especie, que presenta concha sin placas oseas y con una piel queratinizada.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Especies de tortugas marinas divididas en las dos fam\u00edlias existentes<\/strong><\/p>\n<p>Como se menciona anteriormente la familia Dermochelidae contiene una \u00fanica especie, Dermochelys coriacea (tortuga la\u00fad), en cambio la familia Cheloniidae, representa a todas las dem\u00e1s especies existentes, como son; <em>Caretta caretta<\/em> (tortuga boba o cahuama), <em>Chelonia mydas<\/em> (tortuga verde), <em>Eretmochelys imbricata<\/em> (tortuga carey), <em>Lepidochelys olivacea<\/em> (Lepidochelys olivacea o golfina), <em>Lepidochelys kempii<\/em> (tortuga lora o bastarda), <em>natatorios depressus<\/em> (tortuga plana o australiana).<\/p>\n<p>Hay que decir que existen dos poblaciones de tortuga verde <em>Chelonia mydas<\/em>, consideradas como subespecies, <em>Chelonia mydas mydas<\/em> y <em>Chelonia mydas agasizzi.<\/em> La primera poblaci\u00f3n habita en el Atl\u00e1ntico y es m\u00e1s clara de piel por eso se llama tortuga verde o blanca, en cambio <em>Chelonia mydas agassizii<\/em> habita en el Pac\u00edfico y presenta una coloraci\u00f3n m\u00e1s oscura y por eso se llama tortuga negro o prieta.<\/p>\n<p>Para tener una orientaci\u00f3n de la diferencia de tama\u00f1o entre las diferentes especies se puede observar la imagen que se expone a continuaci\u00f3n.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><strong>Hawksbill: Tortuga carei, Olive ridley: tortuga oliv\u00e0cia, Green\/Black: tortuga verda, Kemp\u2019s ridley: tortuga lora, Loggerhead: tortuga caretta, Leatherback: tortuga lla\u00fct, Flatback: Tortuga plana<\/strong><\/p>\n<h3>Morfolog\u00eda y anatom\u00eda<\/h3>\n<p>En referencia a las caracter\u00edsticas morfol\u00f3gicas t\u00edpicas de las tortugas marinas podemos referirnos a su boca de <strong>pico r\u00edgido<\/strong>, el cual no consta de dientes, sino de una potente mand\u00edbula, que utilizan para cortar y masticar los alimentos. Parece ser que perdieron los dientes hace 150-200 millones de a\u00f1os, as\u00ed que en lugar de dientes las mand\u00edbulas est\u00e1n cubiertas por surcos c\u00f3rneos.<\/p>\n<p>En especies carn\u00edvoras suelen estar afilados como cuchillos para poder cortar a sus presas, en cambio las herb\u00edvoras tienen surcos con bordes aserrados para poder cortar las plantas mas duras<\/p>\n<p style=\"text-align: center;\">\n<p>Hace falta mencionar que las tortugas no tienen reflejo de v\u00f3mito. El es\u00f3fago tiene un epitelio estratificado queratinizado con esp\u00edculas c\u00f3rneas. Las esp\u00edculas c\u00f3rneas se disponen dirigidas hacia abajo de manera que ayudan a ingerir el alimento y a triturar las partes duras del alimento.<\/p>\n<p style=\"text-align: center;\">\n<p>Ademas presentan un marcado\u00a0<strong>dimorfismo sexual\u00a0<\/strong>cuando son adultos. Se pueden distinguir por el tama\u00f1o de la cola, mejor en machos que ademas tienen una mayor distancia entre la cloaca y la punta posterior de la cloaca.<\/p>\n<p style=\"text-align: center;\">\n<p>Las tortugas marinas son organismos\u00a0<strong>ectotermos<\/strong>, aunque tienen cierta capacidad termorreguladora. La tortuga La\u00fad es la especie de tortuga que puede soportar temperaturas m\u00e1s bajas, gracias a la presencia de un tejido subcut\u00e1neo muy graso que act\u00faa como aislante.<\/p>\n<p>Todas las\u00a0<strong>extremidades\u00a0<\/strong>son aletas y las aletas anteriores son m\u00e1s largas que las posteriores. Ademas no tienen la cabeza\u00a0<strong>retr\u00e1ctil<\/strong> debido a que presentan las vertebras cervicales unidas.<\/p>\n<p>En referencia a la\u00a0<strong>concha<\/strong>, es aplanada, herm\u00e9tica e hidrodin\u00e1mica para una mayor protecci\u00f3n, velocidad y agilidad en el medio marino. Para conseguir esto han ensanchado y fusionado las costillas y las vertebras de la concha.<\/p>\n<p>La concha esta constituida por placas \u00f3seas internas recubiertas de\u00a0<strong>placas c\u00f3rneas<\/strong>, excepto la la\u00fad que presenta una piel queratinizada y una dermis desarrollada que permite el aislamiento t\u00e9rmico, es la \u00fanica especie capaz de soportar temperaturas m\u00e1s frias.<\/p>\n<p>Las placas c\u00f3rneas que presenta en la cabeza, en la concha y en el plastr\u00f3n nos ayudan a identificar al individuo en funci\u00f3n de la especie que sea.<\/p>\n<p>Como bien hemos mencionado, para identificar la especie de tortuga debemos fijarnos en las placas c\u00f3rneas de la concha, del plastr\u00f3n y de la cabeza.<\/p>\n<p>Las tortugas tienen los <strong>pulmones\u00a0<\/strong>en la parte dorsal del animal, justo despu\u00e9s de la concha, la situaci\u00f3n de esta puede provocar la muerte a una tortuga si la dejas boca arriba, ya que el peso del resto de \u00f3rganos internos y de ella misma aplastar\u00edan los pulmones y los \u00f3rganos.<\/p>\n<p>Las tortugas marinas no disponen de diafragma, el esqueleto que hace que la respiraci\u00f3n sea imposible por movimiento de la caja tor\u00e1cica, y es llevada a cabo principalmente por la acci\u00f3n de las extremidades. Se realiza principalmente por la contracci\u00f3n de los <a href=\"https:\/\/ca.wikipedia.org\/wiki\/M%C3%BAscul\">m\u00fasculos<\/a> abdominales modificados que funcionan de manera <a href=\"https:\/\/ca.wikipedia.org\/wiki\/Analogia_(biologia)\">an\u00e1loga<\/a>\u00a0al\u00a0<a href=\"https:\/\/ca.wikipedia.org\/wiki\/Diafragma_(m%C3%BAscul)\">diafragma<\/a> de los <a href=\"https:\/\/ca.wikipedia.org\/wiki\/Mam%C3%ADfers\">mam\u00edferos<\/a> y por movimientos de bombamiento de la <a href=\"https:\/\/ca.wikipedia.org\/wiki\/Faringe\">faringe<\/a>.<\/p>\n<p>Por este mismo motivo la\u00a0<strong>reanimaci\u00f3n de una tortuga\u00a0<\/strong>debe ser con el movimiento de sus propias aletas. Se debe colocar la mitad posterior de la tortuga m\u00e1s elevada y se debe estirar hacia delante y hacia atr\u00e1s de 6 a 7 veces sus aletas, para que as\u00ed la tortuga oxigene. Seguidamente se deben juntar las aletas al lado del cuello y realizar presi\u00f3n con los pulgares hacia el interior del animal.<\/p>\n<p>El medio marino contiene m\u00e1s sal que el medio terrestre por eso los animales tienen que desarrollar ciertos sistemas para poder regular la salinidad de su cuerpo, ya que no pueden formar una orina hiperosm\u00f3tica. Las tortugas marinas solucionaron el problema con las\u00a0<strong>gl\u00e1ndulas de sal<\/strong>, que son unas gl\u00e1ndulas excretoras de sal situadas en la cabeza. Estas gl\u00e1ndulas de sal regulan la osmosis produciendo soluciones salinas concentradas. Estas secreciones son de 4 a 5 veces mas concentradas que la sangre.<\/p>\n<p>En relaci\u00f3n a esto existe el\u00a0<strong>mito<\/strong> de que las tortugas marinas lloran al salir del agua para poner los huevos. La realidad es que al salir a tierra tienen que compensar la cantidad de sal de su interior con el medio exterior, esto les hace excretar sales por los ojos y da la sensaci\u00f3n de que lloran<\/p>\n<p>Por otro lado a veces sucede un fen\u00f3meno que se denomina llegadas, esto es cuando muchas tortugas marinas de la misma especie llegan a la vez a una misma playa para anidar, actualmente todav\u00eda hay estudios que investigan porque sucede este fen\u00f3meno. Pero todo parece indicar que est\u00e1 relacionado con las\u00a0<strong>Glandulas de Rathke<\/strong>, las cuales no est\u00e1n presentes en todas las especies, tienen una ubicaci\u00f3n variable y una funci\u00f3n bastante desconocida, se cree que estas gl\u00e1ndulas tienen funciones de secreci\u00f3n, para la comunicaci\u00f3n interespec\u00edfica, como inductor de las llegadas y una funci\u00f3n antimicrobiana.<\/p>\n<p>&nbsp;<\/p>\n<p>Bibliografia<\/p>\n<p><a href=\"https:\/\/www.researchgate.net\/figure\/Carapace-in-sea-turtles-A-Caretta-caretta-Left-B-Chelonia-mydas-Right-N_fig2_278121453\">https:\/\/www.researchgate.net\/figure\/Carapace-in-sea-turtles-A-Caretta-caretta-Left-B-Chelonia-mydas-Right-N_fig2_278121453<\/a><\/p>\n<p><a href=\"https:\/\/resistenciarockandroll.wordpress.com\/2017\/05\/30\/anatomia-y-morfologia-tortuga-carey\/\">https:\/\/resistenciarockandroll.wordpress.com\/2017\/05\/30\/anatomia-y-morfologia-tortuga-carey\/<\/a><\/p>\n<p><a href=\"https:\/\/reptiles.paradais-sphynx.com\/informacion\/diferencias-tortugas-marinas-dulceacuicolas-terrestres.htm\">https:\/\/reptiles.paradais-sphynx.com\/informacion\/diferencias-tortugas-marinas-dulceacuicolas-terrestres.htm<\/a><\/p>\n<p><a href=\"https:\/\/studylib.es\/doc\/5187838\/tortugas-marinas-sea-turtles\">https:\/\/studylib.es\/doc\/5187838\/tortugas-marinas-sea-turtles<\/a><\/p>\n<p><a href=\"http:\/\/www.vertebradosibericos.org\/reptiles\/identificacion\/dercorid.html\">http:\/\/www.vertebradosibericos.org\/reptiles\/identificacion\/dercorid.html<\/a><\/p>\n<p><a href=\"http:\/\/www.testudines.org\/es\/articles\/article\/anatomia-del-caparazon-en-las-tortugas-de-caparazon-duro\">http:\/\/www.testudines.org\/es\/articles\/article\/anatomia-del-caparazon-en-las-tortugas-de-caparazon-duro<\/a><\/p>\n<p><a href=\"http:\/\/www.vertebradosibericos.org\/reptiles\/trofico\/carcartr.html\">http:\/\/www.vertebradosibericos.org\/reptiles\/trofico\/carcartr.html<\/a><\/p>\n<p><a href=\"https:\/\/allyouneedisbiology.wordpress.com\/2014\/08\/26\/la-tortuga-boba-caretta-caretta\/\">https:\/\/allyouneedisbiology.wordpress.com\/2014\/08\/26\/la-tortuga-boba-caretta-caretta\/\u00a0<\/a><\/p>\n<p><a href=\"https:\/\/www.fordivers.com\/es\/fauna\/especie\/tortuga-boba\/\">https:\/\/www.fordivers.com\/es\/fauna\/especie\/tortuga-boba\/<\/a><\/p>\n<p><a href=\"https:\/\/www3.gobiernodecanarias.org\/medusa\/wiki\/index.php?title=Tortuga_carey\">https:\/\/www3.gobiernodecanarias.org\/medusa\/wiki\/index.php?title=Tortuga_carey<\/a><\/p>\n<p><a href=\"https:\/\/tortugasmarinas10.info\/plana\/\">https:\/\/tortugasmarinas10.info\/plana\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esta entrada pretende resumir los rasgos caracter\u00edsticos generales de las siete especies de tortugas marinas que hoy en d\u00eda habitan los mares y oc\u00e9anos del  [&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":18519,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[67],"tags":[],"class_list":["post-6206","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-biologia-es"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Esta entrada pretende resumir los rasgos caracter\u00edsticos generales de las siete especies de tortugas marinas que hoy en d\u00eda habitan los mares y oc\u00e9anos del planeta tierra, as\u00ed como los rasgos morfol\u00f3gicos, anat\u00f3micos y adaptaciones fisiol\u00f3gicas de estas. Diferencias entre tortugas terrestres y tortugas marinas Las tortugas marinas, de agua dulce y terrestre presentan morfolog\u00edas\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Ane_admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"j5Te-Y3xjWrjCLJWsYSHtofnTHGBvK1IKvzlSorRXRc\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/anellides.com\/es\/blog\/como-son-las-tortugas-marinas-parte-1\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/blog\\\/como-son-las-tortugas-marinas-parte-1\\\/#article\",\"name\":\"\\u00bfC\\u00f3mo son las tortugas marinas? (parte 1) | Anellides\",\"headline\":\"\\u00bfC\\u00f3mo son las tortugas marinas? (parte 1)\",\"author\":{\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/blog\\\/author\\\/ane_admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/anellides.com\\\/wp-content\\\/files\\\/tortuga-1.jpg\",\"width\":750,\"height\":350},\"datePublished\":\"2020-07-17T11:14:29+00:00\",\"dateModified\":\"2024-08-13T10:10:57+00:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/blog\\\/como-son-las-tortugas-marinas-parte-1\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/blog\\\/como-son-las-tortugas-marinas-parte-1\\\/#webpage\"},\"articleSection\":\"Biologia, Opcional, Optional\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/blog\\\/como-son-las-tortugas-marinas-parte-1\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/anellides.com\\\/es\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/blog\\\/category\\\/biologia-es\\\/#listItem\",\"name\":\"Biologia\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/blog\\\/category\\\/biologia-es\\\/#listItem\",\"position\":2,\"name\":\"Biologia\",\"item\":\"https:\\\/\\\/anellides.com\\\/es\\\/blog\\\/category\\\/biologia-es\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/blog\\\/como-son-las-tortugas-marinas-parte-1\\\/#listItem\",\"name\":\"\\u00bfC\\u00f3mo son las tortugas marinas? (parte 1)\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/blog\\\/como-son-las-tortugas-marinas-parte-1\\\/#listItem\",\"position\":3,\"name\":\"\\u00bfC\\u00f3mo son las tortugas marinas? (parte 1)\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/blog\\\/category\\\/biologia-es\\\/#listItem\",\"name\":\"Biologia\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/#organization\",\"name\":\"Anellides\",\"description\":\"Serveis Ambientals Marins\",\"url\":\"https:\\\/\\\/anellides.com\\\/es\\\/\",\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/anellides\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCY_NA_fh3v8B6uvCKdBLp4A\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/blog\\\/author\\\/ane_admin\\\/#author\",\"url\":\"https:\\\/\\\/anellides.com\\\/es\\\/blog\\\/author\\\/ane_admin\\\/\",\"name\":\"Ane_admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/blog\\\/como-son-las-tortugas-marinas-parte-1\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/128ddaa8fd25bf4339cb192ade2a01e84e20a555b66442ee33957ea7b9aaca15?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Ane_admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/blog\\\/como-son-las-tortugas-marinas-parte-1\\\/#webpage\",\"url\":\"https:\\\/\\\/anellides.com\\\/es\\\/blog\\\/como-son-las-tortugas-marinas-parte-1\\\/\",\"name\":\"\\u00bfC\\u00f3mo son las tortugas marinas? (parte 1) | Anellides\",\"description\":\"Esta entrada pretende resumir los rasgos caracter\\u00edsticos generales de las siete especies de tortugas marinas que hoy en d\\u00eda habitan los mares y oc\\u00e9anos del planeta tierra, as\\u00ed como los rasgos morfol\\u00f3gicos, anat\\u00f3micos y adaptaciones fisiol\\u00f3gicas de estas. Diferencias entre tortugas terrestres y tortugas marinas Las tortugas marinas, de agua dulce y terrestre presentan morfolog\\u00edas\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/blog\\\/como-son-las-tortugas-marinas-parte-1\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/blog\\\/author\\\/ane_admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/blog\\\/author\\\/ane_admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/anellides.com\\\/wp-content\\\/files\\\/tortuga-1.jpg\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/blog\\\/como-son-las-tortugas-marinas-parte-1\\\/#mainImage\",\"width\":750,\"height\":350},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/blog\\\/como-son-las-tortugas-marinas-parte-1\\\/#mainImage\"},\"datePublished\":\"2020-07-17T11:14:29+00:00\",\"dateModified\":\"2024-08-13T10:10:57+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/anellides.com\\\/es\\\/\",\"name\":\"Anellides\",\"description\":\"Serveis Ambientals Marins\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"\u00bfC\u00f3mo son las tortugas marinas? (parte 1) | Anellides","description":"Esta entrada pretende resumir los rasgos caracter\u00edsticos generales de las siete especies de tortugas marinas que hoy en d\u00eda habitan los mares y oc\u00e9anos del planeta tierra, as\u00ed como los rasgos morfol\u00f3gicos, anat\u00f3micos y adaptaciones fisiol\u00f3gicas de estas. Diferencias entre tortugas terrestres y tortugas marinas Las tortugas marinas, de agua dulce y terrestre presentan morfolog\u00edas","canonical_url":"https:\/\/anellides.com\/es\/blog\/como-son-las-tortugas-marinas-parte-1\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"j5Te-Y3xjWrjCLJWsYSHtofnTHGBvK1IKvzlSorRXRc","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/anellides.com\/es\/blog\/como-son-las-tortugas-marinas-parte-1\/#article","name":"\u00bfC\u00f3mo son las tortugas marinas? (parte 1) | Anellides","headline":"\u00bfC\u00f3mo son las tortugas marinas? (parte 1)","author":{"@id":"https:\/\/anellides.com\/es\/blog\/author\/ane_admin\/#author"},"publisher":{"@id":"https:\/\/anellides.com\/es\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/anellides.com\/wp-content\/files\/tortuga-1.jpg","width":750,"height":350},"datePublished":"2020-07-17T11:14:29+00:00","dateModified":"2024-08-13T10:10:57+00:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/anellides.com\/es\/blog\/como-son-las-tortugas-marinas-parte-1\/#webpage"},"isPartOf":{"@id":"https:\/\/anellides.com\/es\/blog\/como-son-las-tortugas-marinas-parte-1\/#webpage"},"articleSection":"Biologia, Opcional, Optional"},{"@type":"BreadcrumbList","@id":"https:\/\/anellides.com\/es\/blog\/como-son-las-tortugas-marinas-parte-1\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/anellides.com\/es\/#listItem","position":1,"name":"Home","item":"https:\/\/anellides.com\/es\/","nextItem":{"@type":"ListItem","@id":"https:\/\/anellides.com\/es\/blog\/category\/biologia-es\/#listItem","name":"Biologia"}},{"@type":"ListItem","@id":"https:\/\/anellides.com\/es\/blog\/category\/biologia-es\/#listItem","position":2,"name":"Biologia","item":"https:\/\/anellides.com\/es\/blog\/category\/biologia-es\/","nextItem":{"@type":"ListItem","@id":"https:\/\/anellides.com\/es\/blog\/como-son-las-tortugas-marinas-parte-1\/#listItem","name":"\u00bfC\u00f3mo son las tortugas marinas? (parte 1)"},"previousItem":{"@type":"ListItem","@id":"https:\/\/anellides.com\/es\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/anellides.com\/es\/blog\/como-son-las-tortugas-marinas-parte-1\/#listItem","position":3,"name":"\u00bfC\u00f3mo son las tortugas marinas? (parte 1)","previousItem":{"@type":"ListItem","@id":"https:\/\/anellides.com\/es\/blog\/category\/biologia-es\/#listItem","name":"Biologia"}}]},{"@type":"Organization","@id":"https:\/\/anellides.com\/es\/#organization","name":"Anellides","description":"Serveis Ambientals Marins","url":"https:\/\/anellides.com\/es\/","sameAs":["https:\/\/www.instagram.com\/anellides\/","https:\/\/www.youtube.com\/channel\/UCY_NA_fh3v8B6uvCKdBLp4A"]},{"@type":"Person","@id":"https:\/\/anellides.com\/es\/blog\/author\/ane_admin\/#author","url":"https:\/\/anellides.com\/es\/blog\/author\/ane_admin\/","name":"Ane_admin","image":{"@type":"ImageObject","@id":"https:\/\/anellides.com\/es\/blog\/como-son-las-tortugas-marinas-parte-1\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/128ddaa8fd25bf4339cb192ade2a01e84e20a555b66442ee33957ea7b9aaca15?s=96&d=mm&r=g","width":96,"height":96,"caption":"Ane_admin"}},{"@type":"WebPage","@id":"https:\/\/anellides.com\/es\/blog\/como-son-las-tortugas-marinas-parte-1\/#webpage","url":"https:\/\/anellides.com\/es\/blog\/como-son-las-tortugas-marinas-parte-1\/","name":"\u00bfC\u00f3mo son las tortugas marinas? (parte 1) | Anellides","description":"Esta entrada pretende resumir los rasgos caracter\u00edsticos generales de las siete especies de tortugas marinas que hoy en d\u00eda habitan los mares y oc\u00e9anos del planeta tierra, as\u00ed como los rasgos morfol\u00f3gicos, anat\u00f3micos y adaptaciones fisiol\u00f3gicas de estas. Diferencias entre tortugas terrestres y tortugas marinas Las tortugas marinas, de agua dulce y terrestre presentan morfolog\u00edas","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/anellides.com\/es\/#website"},"breadcrumb":{"@id":"https:\/\/anellides.com\/es\/blog\/como-son-las-tortugas-marinas-parte-1\/#breadcrumblist"},"author":{"@id":"https:\/\/anellides.com\/es\/blog\/author\/ane_admin\/#author"},"creator":{"@id":"https:\/\/anellides.com\/es\/blog\/author\/ane_admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/anellides.com\/wp-content\/files\/tortuga-1.jpg","@id":"https:\/\/anellides.com\/es\/blog\/como-son-las-tortugas-marinas-parte-1\/#mainImage","width":750,"height":350},"primaryImageOfPage":{"@id":"https:\/\/anellides.com\/es\/blog\/como-son-las-tortugas-marinas-parte-1\/#mainImage"},"datePublished":"2020-07-17T11:14:29+00:00","dateModified":"2024-08-13T10:10:57+00:00"},{"@type":"WebSite","@id":"https:\/\/anellides.com\/es\/#website","url":"https:\/\/anellides.com\/es\/","name":"Anellides","description":"Serveis Ambientals Marins","inLanguage":"es-ES","publisher":{"@id":"https:\/\/anellides.com\/es\/#organization"}}]}},"aioseo_meta_data":{"post_id":"6206","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-03-25 18:20:26","updated":"2025-06-04 12:31:05","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/anellides.com\/es\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/anellides.com\/es\/blog\/category\/biologia-es\/\" title=\"Biologia\">Biologia<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t\u00bfC\u00f3mo son las tortugas marinas? (parte 1)\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/anellides.com\/es\/"},{"label":"Biologia","link":"https:\/\/anellides.com\/es\/blog\/category\/biologia-es\/"},{"label":"\u00bfC\u00f3mo son las tortugas marinas? (parte 1)","link":"https:\/\/anellides.com\/es\/blog\/como-son-las-tortugas-marinas-parte-1\/"}],"_links":{"self":[{"href":"https:\/\/anellides.com\/es\/wp-json\/wp\/v2\/posts\/6206","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/anellides.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/anellides.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/anellides.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/anellides.com\/es\/wp-json\/wp\/v2\/comments?post=6206"}],"version-history":[{"count":2,"href":"https:\/\/anellides.com\/es\/wp-json\/wp\/v2\/posts\/6206\/revisions"}],"predecessor-version":[{"id":18499,"href":"https:\/\/anellides.com\/es\/wp-json\/wp\/v2\/posts\/6206\/revisions\/18499"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/anellides.com\/es\/wp-json\/wp\/v2\/media\/18519"}],"wp:attachment":[{"href":"https:\/\/anellides.com\/es\/wp-json\/wp\/v2\/media?parent=6206"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/anellides.com\/es\/wp-json\/wp\/v2\/categories?post=6206"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/anellides.com\/es\/wp-json\/wp\/v2\/tags?post=6206"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}