{"id":13051,"date":"2023-12-12T06:50:31","date_gmt":"2023-12-12T06:50:31","guid":{"rendered":"https:\/\/anellides.com\/?post_type=product&#038;p=13051"},"modified":"2024-03-11T10:58:46","modified_gmt":"2024-03-11T10:58:46","slug":"cuento-anna-habla-con-los-peces","status":"publish","type":"product","link":"https:\/\/anellides.com\/es\/producto\/cuento-anna-habla-con-los-peces\/","title":{"rendered":"Cuento: Anna habla con los peces"},"content":{"rendered":"<p>Cada tarde Anna sale con su barquita y se va hasta un islote a pescar. Pero una tarde, una ola inesperada deja un pez extra\u00f1o sobre la roca. Cuando Anna est\u00e1 a punto de capturarlo, el pez le habla y le pide que le perdone. Para agradecerle, le regala un don: nadar como un pez y se ofrece a ser su gu\u00eda por las profundidades. Y es as\u00ed como comienza una fascinante aventura submarina, a trav\u00e9s de la cual la ni\u00f1a y el lector aprender\u00e1n a identificar a los peces y descubrir\u00e1n algunos de sus secretos mejor guardados.<br \/>\nCon este libro, tanto los ni\u00f1os como las familias aprender\u00e1n y disfrutar\u00e1n del mundo de los peces.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gui\u00f3n e ilustraci\u00f3n: <strong>Mag\u00ed Marc\u00e9<\/strong><br \/>\nEditorial: <strong>La Cua<\/strong><br \/>\nA\u00f1o de edici\u00f3n: <strong>2013<\/strong><br \/>\nISBN: 9788461644605<br \/>\nMateria: <strong>Peces del Mediterr\u00e1neo<\/strong><\/p>\n","protected":false},"featured_media":15018,"comment_status":"open","ping_status":"open","template":"","meta":[],"product_brand":[],"product_cat":[160],"product_tag":[],"class_list":["post-13051","product","type-product","status-publish","has-post-thumbnail","product_cat-llibres-es","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Gui\u00f3n e ilustraci\u00f3n: Mag\u00ed Marc\u00e9 Editorial: La Cua A\u00f1o de edici\u00f3n: 2013 ISBN: 9788461644605 Materia: Peces del Mediterr\u00e1neo\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"google-site-verification\" content=\"j5Te-Y3xjWrjCLJWsYSHtofnTHGBvK1IKvzlSorRXRc\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/anellides.com\/es\/producto\/cuento-anna-habla-con-los-peces\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/producto\\\/cuento-anna-habla-con-los-peces\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/anellides.com\\\/es\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/tienda\\\/#listItem\",\"name\":\"Tienda\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/tienda\\\/#listItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\\\/\\\/anellides.com\\\/es\\\/tienda\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/product-category\\\/llibres-es\\\/#listItem\",\"name\":\"Llibres\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/product-category\\\/llibres-es\\\/#listItem\",\"position\":3,\"name\":\"Llibres\",\"item\":\"https:\\\/\\\/anellides.com\\\/es\\\/product-category\\\/llibres-es\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/producto\\\/cuento-anna-habla-con-los-peces\\\/#listItem\",\"name\":\"Cuento: Anna habla con los peces\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/tienda\\\/#listItem\",\"name\":\"Tienda\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/producto\\\/cuento-anna-habla-con-los-peces\\\/#listItem\",\"position\":4,\"name\":\"Cuento: Anna habla con los peces\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/product-category\\\/llibres-es\\\/#listItem\",\"name\":\"Llibres\"}}]},{\"@type\":\"ItemPage\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/producto\\\/cuento-anna-habla-con-los-peces\\\/#itempage\",\"url\":\"https:\\\/\\\/anellides.com\\\/es\\\/producto\\\/cuento-anna-habla-con-los-peces\\\/\",\"name\":\"Cuento: Anna habla con los peces | Anellides\",\"description\":\"Gui\\u00f3n e ilustraci\\u00f3n: Mag\\u00ed Marc\\u00e9 Editorial: La Cua A\\u00f1o de edici\\u00f3n: 2013 ISBN: 9788461644605 Materia: Peces del Mediterr\\u00e1neo\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/producto\\\/cuento-anna-habla-con-los-peces\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/anellides.com\\\/wp-content\\\/files\\\/lana-parla-amb-els-peixos.png\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/producto\\\/cuento-anna-habla-con-los-peces\\\/#mainImage\",\"width\":831,\"height\":541},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/producto\\\/cuento-anna-habla-con-los-peces\\\/#mainImage\"},\"datePublished\":\"2023-12-12T06:50:31+00:00\",\"dateModified\":\"2024-03-11T10:58:46+00:00\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/#organization\",\"name\":\"Anellides\",\"description\":\"Serveis Ambientals Marins\",\"url\":\"https:\\\/\\\/anellides.com\\\/es\\\/\",\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/anellides\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCY_NA_fh3v8B6uvCKdBLp4A\"]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/anellides.com\\\/es\\\/\",\"name\":\"Anellides\",\"description\":\"Serveis Ambientals Marins\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Cuento: Anna habla con los peces | Anellides","description":"Gui\u00f3n e ilustraci\u00f3n: Mag\u00ed Marc\u00e9 Editorial: La Cua A\u00f1o de edici\u00f3n: 2013 ISBN: 9788461644605 Materia: Peces del Mediterr\u00e1neo","canonical_url":"https:\/\/anellides.com\/es\/producto\/cuento-anna-habla-con-los-peces\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"j5Te-Y3xjWrjCLJWsYSHtofnTHGBvK1IKvzlSorRXRc","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/anellides.com\/es\/producto\/cuento-anna-habla-con-los-peces\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/anellides.com\/es\/#listItem","position":1,"name":"Home","item":"https:\/\/anellides.com\/es\/","nextItem":{"@type":"ListItem","@id":"https:\/\/anellides.com\/es\/tienda\/#listItem","name":"Tienda"}},{"@type":"ListItem","@id":"https:\/\/anellides.com\/es\/tienda\/#listItem","position":2,"name":"Tienda","item":"https:\/\/anellides.com\/es\/tienda\/","nextItem":{"@type":"ListItem","@id":"https:\/\/anellides.com\/es\/product-category\/llibres-es\/#listItem","name":"Llibres"},"previousItem":{"@type":"ListItem","@id":"https:\/\/anellides.com\/es\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/anellides.com\/es\/product-category\/llibres-es\/#listItem","position":3,"name":"Llibres","item":"https:\/\/anellides.com\/es\/product-category\/llibres-es\/","nextItem":{"@type":"ListItem","@id":"https:\/\/anellides.com\/es\/producto\/cuento-anna-habla-con-los-peces\/#listItem","name":"Cuento: Anna habla con los peces"},"previousItem":{"@type":"ListItem","@id":"https:\/\/anellides.com\/es\/tienda\/#listItem","name":"Tienda"}},{"@type":"ListItem","@id":"https:\/\/anellides.com\/es\/producto\/cuento-anna-habla-con-los-peces\/#listItem","position":4,"name":"Cuento: Anna habla con los peces","previousItem":{"@type":"ListItem","@id":"https:\/\/anellides.com\/es\/product-category\/llibres-es\/#listItem","name":"Llibres"}}]},{"@type":"ItemPage","@id":"https:\/\/anellides.com\/es\/producto\/cuento-anna-habla-con-los-peces\/#itempage","url":"https:\/\/anellides.com\/es\/producto\/cuento-anna-habla-con-los-peces\/","name":"Cuento: Anna habla con los peces | Anellides","description":"Gui\u00f3n e ilustraci\u00f3n: Mag\u00ed Marc\u00e9 Editorial: La Cua A\u00f1o de edici\u00f3n: 2013 ISBN: 9788461644605 Materia: Peces del Mediterr\u00e1neo","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/anellides.com\/es\/#website"},"breadcrumb":{"@id":"https:\/\/anellides.com\/es\/producto\/cuento-anna-habla-con-los-peces\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/anellides.com\/wp-content\/files\/lana-parla-amb-els-peixos.png","@id":"https:\/\/anellides.com\/es\/producto\/cuento-anna-habla-con-los-peces\/#mainImage","width":831,"height":541},"primaryImageOfPage":{"@id":"https:\/\/anellides.com\/es\/producto\/cuento-anna-habla-con-los-peces\/#mainImage"},"datePublished":"2023-12-12T06:50:31+00:00","dateModified":"2024-03-11T10:58:46+00:00"},{"@type":"Organization","@id":"https:\/\/anellides.com\/es\/#organization","name":"Anellides","description":"Serveis Ambientals Marins","url":"https:\/\/anellides.com\/es\/","sameAs":["https:\/\/www.instagram.com\/anellides\/","https:\/\/www.youtube.com\/channel\/UCY_NA_fh3v8B6uvCKdBLp4A"]},{"@type":"WebSite","@id":"https:\/\/anellides.com\/es\/#website","url":"https:\/\/anellides.com\/es\/","name":"Anellides","description":"Serveis Ambientals Marins","inLanguage":"es-ES","publisher":{"@id":"https:\/\/anellides.com\/es\/#organization"}}]}},"aioseo_meta_data":{"post_id":"13051","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"ItemPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"}}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-12-12 06:46:20","updated":"2025-06-04 12:46:39","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/anellides.com\/es\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/anellides.com\/es\/tienda\/\" title=\"Tienda\">Tienda<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/anellides.com\/es\/product-category\/llibres-es\/\" title=\"Llibres\">Llibres<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tCuento: Anna habla con los peces\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/anellides.com\/es\/"},{"label":"Tienda","link":"https:\/\/anellides.com\/es\/tienda\/"},{"label":"Llibres","link":"https:\/\/anellides.com\/es\/product-category\/llibres-es\/"},{"label":"Cuento: Anna habla con los peces","link":"https:\/\/anellides.com\/es\/producto\/cuento-anna-habla-con-los-peces\/"}],"_links":{"self":[{"href":"https:\/\/anellides.com\/es\/wp-json\/wp\/v2\/product\/13051","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/anellides.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/anellides.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/anellides.com\/es\/wp-json\/wp\/v2\/comments?post=13051"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/anellides.com\/es\/wp-json\/wp\/v2\/media\/15018"}],"wp:attachment":[{"href":"https:\/\/anellides.com\/es\/wp-json\/wp\/v2\/media?parent=13051"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/anellides.com\/es\/wp-json\/wp\/v2\/product_brand?post=13051"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/anellides.com\/es\/wp-json\/wp\/v2\/product_cat?post=13051"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/anellides.com\/es\/wp-json\/wp\/v2\/product_tag?post=13051"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}