{"id":13055,"date":"2023-12-12T07:05:41","date_gmt":"2023-12-12T07:05:41","guid":{"rendered":"https:\/\/anellides.com\/?post_type=product&#038;p=13055"},"modified":"2024-03-11T10:56:04","modified_gmt":"2024-03-11T10:56:04","slug":"cuento-anna-y-el-misterio-de-los-peces-abisales","status":"publish","type":"product","link":"https:\/\/anellides.com\/es\/producto\/cuento-anna-y-el-misterio-de-los-peces-abisales\/","title":{"rendered":"Cuento: Anna y el misterio de los peces abisales"},"content":{"rendered":"<p>Esta vez nuestra amiga Anna, se sumerge hasta los 1.000 metros de profundidad para conocer a los peces abisales. Descubriremos un mundo todav\u00eda desconocido por todos nosotros. En las fr\u00edas y oscuras aguas abisales nuestra hero\u00edna nadar\u00e1 con su amigo el pez Oscar junto a los seres m\u00e1s sorprendentes de nuestro mundo. Peces hambrientos con grandes bocas, Peces con luces, gambas, calamares gigantes y muchas m\u00e1s sorpresas, te est\u00e1n esperando en esta fascinante y peligrosa aventura.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gui\u00f3n e ilustraci\u00f3n: <strong>Mag\u00ed Marc\u00e9<\/strong><br \/>\nEditorial: <strong>La Cua<\/strong><br \/>\nA\u00f1o de edici\u00f3n: <strong>2016<\/strong><br \/>\nISBN: <strong>9788460683834<\/strong><br \/>\nMateria: <strong>Peces del Mediterr\u00e1neo<\/strong><\/p>\n","protected":false},"featured_media":15118,"comment_status":"open","ping_status":"open","template":"","meta":[],"product_brand":[],"product_cat":[160],"product_tag":[],"class_list":["post-13055","product","type-product","status-publish","has-post-thumbnail","product_cat-llibres-es","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Gui\u00f3n e ilustraci\u00f3n: Mag\u00ed Marc\u00e9 Editorial: La Cua A\u00f1o de edici\u00f3n: 2016 ISBN: 9788460683834 Materia: Peces del Mediterr\u00e1neo\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"google-site-verification\" content=\"j5Te-Y3xjWrjCLJWsYSHtofnTHGBvK1IKvzlSorRXRc\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/anellides.com\/es\/producto\/cuento-anna-y-el-misterio-de-los-peces-abisales\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/producto\\\/cuento-anna-y-el-misterio-de-los-peces-abisales\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/anellides.com\\\/es\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/tienda\\\/#listItem\",\"name\":\"Tienda\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/tienda\\\/#listItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\\\/\\\/anellides.com\\\/es\\\/tienda\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/product-category\\\/llibres-es\\\/#listItem\",\"name\":\"Llibres\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/product-category\\\/llibres-es\\\/#listItem\",\"position\":3,\"name\":\"Llibres\",\"item\":\"https:\\\/\\\/anellides.com\\\/es\\\/product-category\\\/llibres-es\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/producto\\\/cuento-anna-y-el-misterio-de-los-peces-abisales\\\/#listItem\",\"name\":\"Cuento: Anna y el misterio de los peces abisales\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/tienda\\\/#listItem\",\"name\":\"Tienda\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/producto\\\/cuento-anna-y-el-misterio-de-los-peces-abisales\\\/#listItem\",\"position\":4,\"name\":\"Cuento: Anna y el misterio de los peces abisales\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/product-category\\\/llibres-es\\\/#listItem\",\"name\":\"Llibres\"}}]},{\"@type\":\"ItemPage\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/producto\\\/cuento-anna-y-el-misterio-de-los-peces-abisales\\\/#itempage\",\"url\":\"https:\\\/\\\/anellides.com\\\/es\\\/producto\\\/cuento-anna-y-el-misterio-de-los-peces-abisales\\\/\",\"name\":\"Cuento: Anna y el misterio de los peces abisales | Anellides\",\"description\":\"Gui\\u00f3n e ilustraci\\u00f3n: Mag\\u00ed Marc\\u00e9 Editorial: La Cua A\\u00f1o de edici\\u00f3n: 2016 ISBN: 9788460683834 Materia: Peces del Mediterr\\u00e1neo\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/producto\\\/cuento-anna-y-el-misterio-de-los-peces-abisales\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/anellides.com\\\/wp-content\\\/files\\\/el-misteria-dels-peixos-abissals.jpg\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/producto\\\/cuento-anna-y-el-misterio-de-los-peces-abisales\\\/#mainImage\",\"width\":1843,\"height\":1200},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/producto\\\/cuento-anna-y-el-misterio-de-los-peces-abisales\\\/#mainImage\"},\"datePublished\":\"2023-12-12T07:05:41+00:00\",\"dateModified\":\"2024-03-11T10:56:04+00:00\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/#organization\",\"name\":\"Anellides\",\"description\":\"Serveis Ambientals Marins\",\"url\":\"https:\\\/\\\/anellides.com\\\/es\\\/\",\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/anellides\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCY_NA_fh3v8B6uvCKdBLp4A\"]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/anellides.com\\\/es\\\/\",\"name\":\"Anellides\",\"description\":\"Serveis Ambientals Marins\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Cuento: Anna y el misterio de los peces abisales | Anellides","description":"Gui\u00f3n e ilustraci\u00f3n: Mag\u00ed Marc\u00e9 Editorial: La Cua A\u00f1o de edici\u00f3n: 2016 ISBN: 9788460683834 Materia: Peces del Mediterr\u00e1neo","canonical_url":"https:\/\/anellides.com\/es\/producto\/cuento-anna-y-el-misterio-de-los-peces-abisales\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"j5Te-Y3xjWrjCLJWsYSHtofnTHGBvK1IKvzlSorRXRc","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/anellides.com\/es\/producto\/cuento-anna-y-el-misterio-de-los-peces-abisales\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/anellides.com\/es\/#listItem","position":1,"name":"Home","item":"https:\/\/anellides.com\/es\/","nextItem":{"@type":"ListItem","@id":"https:\/\/anellides.com\/es\/tienda\/#listItem","name":"Tienda"}},{"@type":"ListItem","@id":"https:\/\/anellides.com\/es\/tienda\/#listItem","position":2,"name":"Tienda","item":"https:\/\/anellides.com\/es\/tienda\/","nextItem":{"@type":"ListItem","@id":"https:\/\/anellides.com\/es\/product-category\/llibres-es\/#listItem","name":"Llibres"},"previousItem":{"@type":"ListItem","@id":"https:\/\/anellides.com\/es\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/anellides.com\/es\/product-category\/llibres-es\/#listItem","position":3,"name":"Llibres","item":"https:\/\/anellides.com\/es\/product-category\/llibres-es\/","nextItem":{"@type":"ListItem","@id":"https:\/\/anellides.com\/es\/producto\/cuento-anna-y-el-misterio-de-los-peces-abisales\/#listItem","name":"Cuento: Anna y el misterio de los peces abisales"},"previousItem":{"@type":"ListItem","@id":"https:\/\/anellides.com\/es\/tienda\/#listItem","name":"Tienda"}},{"@type":"ListItem","@id":"https:\/\/anellides.com\/es\/producto\/cuento-anna-y-el-misterio-de-los-peces-abisales\/#listItem","position":4,"name":"Cuento: Anna y el misterio de los peces abisales","previousItem":{"@type":"ListItem","@id":"https:\/\/anellides.com\/es\/product-category\/llibres-es\/#listItem","name":"Llibres"}}]},{"@type":"ItemPage","@id":"https:\/\/anellides.com\/es\/producto\/cuento-anna-y-el-misterio-de-los-peces-abisales\/#itempage","url":"https:\/\/anellides.com\/es\/producto\/cuento-anna-y-el-misterio-de-los-peces-abisales\/","name":"Cuento: Anna y el misterio de los peces abisales | Anellides","description":"Gui\u00f3n e ilustraci\u00f3n: Mag\u00ed Marc\u00e9 Editorial: La Cua A\u00f1o de edici\u00f3n: 2016 ISBN: 9788460683834 Materia: Peces del Mediterr\u00e1neo","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/anellides.com\/es\/#website"},"breadcrumb":{"@id":"https:\/\/anellides.com\/es\/producto\/cuento-anna-y-el-misterio-de-los-peces-abisales\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/anellides.com\/wp-content\/files\/el-misteria-dels-peixos-abissals.jpg","@id":"https:\/\/anellides.com\/es\/producto\/cuento-anna-y-el-misterio-de-los-peces-abisales\/#mainImage","width":1843,"height":1200},"primaryImageOfPage":{"@id":"https:\/\/anellides.com\/es\/producto\/cuento-anna-y-el-misterio-de-los-peces-abisales\/#mainImage"},"datePublished":"2023-12-12T07:05:41+00:00","dateModified":"2024-03-11T10:56:04+00:00"},{"@type":"Organization","@id":"https:\/\/anellides.com\/es\/#organization","name":"Anellides","description":"Serveis Ambientals Marins","url":"https:\/\/anellides.com\/es\/","sameAs":["https:\/\/www.instagram.com\/anellides\/","https:\/\/www.youtube.com\/channel\/UCY_NA_fh3v8B6uvCKdBLp4A"]},{"@type":"WebSite","@id":"https:\/\/anellides.com\/es\/#website","url":"https:\/\/anellides.com\/es\/","name":"Anellides","description":"Serveis Ambientals Marins","inLanguage":"es-ES","publisher":{"@id":"https:\/\/anellides.com\/es\/#organization"}}]}},"aioseo_meta_data":{"post_id":"13055","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"ItemPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"}}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-12-12 07:02:10","updated":"2025-06-04 12:46:39","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/anellides.com\/es\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/anellides.com\/es\/tienda\/\" title=\"Tienda\">Tienda<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/anellides.com\/es\/product-category\/llibres-es\/\" title=\"Llibres\">Llibres<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tCuento: Anna y el misterio de los peces abisales\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/anellides.com\/es\/"},{"label":"Tienda","link":"https:\/\/anellides.com\/es\/tienda\/"},{"label":"Llibres","link":"https:\/\/anellides.com\/es\/product-category\/llibres-es\/"},{"label":"Cuento: Anna y el misterio de los peces abisales","link":"https:\/\/anellides.com\/es\/producto\/cuento-anna-y-el-misterio-de-los-peces-abisales\/"}],"_links":{"self":[{"href":"https:\/\/anellides.com\/es\/wp-json\/wp\/v2\/product\/13055","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/anellides.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/anellides.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/anellides.com\/es\/wp-json\/wp\/v2\/comments?post=13055"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/anellides.com\/es\/wp-json\/wp\/v2\/media\/15118"}],"wp:attachment":[{"href":"https:\/\/anellides.com\/es\/wp-json\/wp\/v2\/media?parent=13055"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/anellides.com\/es\/wp-json\/wp\/v2\/product_brand?post=13055"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/anellides.com\/es\/wp-json\/wp\/v2\/product_cat?post=13055"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/anellides.com\/es\/wp-json\/wp\/v2\/product_tag?post=13055"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}