{"id":18994,"date":"2025-01-10T08:30:23","date_gmt":"2025-01-10T09:13:14","guid":{"rendered":"https:\/\/anellides.com\/product\/libro-lanna-y-los-secretos-de-los-peces-de-arena\/"},"modified":"2025-01-10T09:13:14","modified_gmt":"2025-01-10T09:13:14","slug":"libro-lanna-y-los-secretos-de-los-peces-de-arena","status":"publish","type":"product","link":"https:\/\/anellides.com\/es\/producto\/libro-lanna-y-los-secretos-de-los-peces-de-arena\/","title":{"rendered":"Libro L&#8217;anna y los secretos de los peces de arena"},"content":{"rendered":"<p><span data-olk-copy-source=\"MessageBody\">Libro L&#8217;anna y los secretos de los peces de arena<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p><span data-olk-copy-source=\"MessageBody\">Libro L&#8217;anna y los secretos de los peces de arena<\/span><\/p>\n","protected":false},"featured_media":18993,"comment_status":"open","ping_status":"open","template":"","meta":[],"product_brand":[],"product_cat":[160],"product_tag":[],"class_list":["post-18994","product","type-product","status-publish","has-post-thumbnail","product_cat-llibres-es","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Libro L&#039;anna y los secretos de los peces de arena\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"google-site-verification\" content=\"j5Te-Y3xjWrjCLJWsYSHtofnTHGBvK1IKvzlSorRXRc\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/anellides.com\/es\/producto\/libro-lanna-y-los-secretos-de-los-peces-de-arena\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/producto\\\/libro-lanna-y-los-secretos-de-los-peces-de-arena\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/anellides.com\\\/es\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/tienda\\\/#listItem\",\"name\":\"Tienda\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/tienda\\\/#listItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\\\/\\\/anellides.com\\\/es\\\/tienda\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/product-category\\\/llibres-es\\\/#listItem\",\"name\":\"Llibres\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/product-category\\\/llibres-es\\\/#listItem\",\"position\":3,\"name\":\"Llibres\",\"item\":\"https:\\\/\\\/anellides.com\\\/es\\\/product-category\\\/llibres-es\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/producto\\\/libro-lanna-y-los-secretos-de-los-peces-de-arena\\\/#listItem\",\"name\":\"Libro L&#8217;anna y los secretos de los peces de arena\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/tienda\\\/#listItem\",\"name\":\"Tienda\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/producto\\\/libro-lanna-y-los-secretos-de-los-peces-de-arena\\\/#listItem\",\"position\":4,\"name\":\"Libro L&#8217;anna y los secretos de los peces de arena\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/product-category\\\/llibres-es\\\/#listItem\",\"name\":\"Llibres\"}}]},{\"@type\":\"ItemPage\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/producto\\\/libro-lanna-y-los-secretos-de-los-peces-de-arena\\\/#itempage\",\"url\":\"https:\\\/\\\/anellides.com\\\/es\\\/producto\\\/libro-lanna-y-los-secretos-de-los-peces-de-arena\\\/\",\"name\":\"Libro L\\u2019anna y los secretos de los peces de arena | Anellides\",\"description\":\"Libro L'anna y los secretos de los peces de arena\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/producto\\\/libro-lanna-y-los-secretos-de-los-peces-de-arena\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/anellides.com\\\/wp-content\\\/files\\\/Llibre-Lanna-i-els-secrets-dels-peixos-de-sorra.jpg\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/producto\\\/libro-lanna-y-los-secretos-de-los-peces-de-arena\\\/#mainImage\",\"width\":900,\"height\":586,\"caption\":\"Llibre L'anna i els secrets dels peixos de sorra\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/producto\\\/libro-lanna-y-los-secretos-de-los-peces-de-arena\\\/#mainImage\"},\"datePublished\":\"2025-01-10T08:30:23+00:00\",\"dateModified\":\"2025-01-10T09:13:14+00:00\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/#organization\",\"name\":\"Anellides\",\"description\":\"Serveis Ambientals Marins\",\"url\":\"https:\\\/\\\/anellides.com\\\/es\\\/\",\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/anellides\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCY_NA_fh3v8B6uvCKdBLp4A\"]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/anellides.com\\\/es\\\/\",\"name\":\"Anellides\",\"description\":\"Serveis Ambientals Marins\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Libro L\u2019anna y los secretos de los peces de arena | Anellides","description":"Libro L'anna y los secretos de los peces de arena","canonical_url":"https:\/\/anellides.com\/es\/producto\/libro-lanna-y-los-secretos-de-los-peces-de-arena\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"j5Te-Y3xjWrjCLJWsYSHtofnTHGBvK1IKvzlSorRXRc","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/anellides.com\/es\/producto\/libro-lanna-y-los-secretos-de-los-peces-de-arena\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/anellides.com\/es\/#listItem","position":1,"name":"Home","item":"https:\/\/anellides.com\/es\/","nextItem":{"@type":"ListItem","@id":"https:\/\/anellides.com\/es\/tienda\/#listItem","name":"Tienda"}},{"@type":"ListItem","@id":"https:\/\/anellides.com\/es\/tienda\/#listItem","position":2,"name":"Tienda","item":"https:\/\/anellides.com\/es\/tienda\/","nextItem":{"@type":"ListItem","@id":"https:\/\/anellides.com\/es\/product-category\/llibres-es\/#listItem","name":"Llibres"},"previousItem":{"@type":"ListItem","@id":"https:\/\/anellides.com\/es\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/anellides.com\/es\/product-category\/llibres-es\/#listItem","position":3,"name":"Llibres","item":"https:\/\/anellides.com\/es\/product-category\/llibres-es\/","nextItem":{"@type":"ListItem","@id":"https:\/\/anellides.com\/es\/producto\/libro-lanna-y-los-secretos-de-los-peces-de-arena\/#listItem","name":"Libro L&#8217;anna y los secretos de los peces de arena"},"previousItem":{"@type":"ListItem","@id":"https:\/\/anellides.com\/es\/tienda\/#listItem","name":"Tienda"}},{"@type":"ListItem","@id":"https:\/\/anellides.com\/es\/producto\/libro-lanna-y-los-secretos-de-los-peces-de-arena\/#listItem","position":4,"name":"Libro L&#8217;anna y los secretos de los peces de arena","previousItem":{"@type":"ListItem","@id":"https:\/\/anellides.com\/es\/product-category\/llibres-es\/#listItem","name":"Llibres"}}]},{"@type":"ItemPage","@id":"https:\/\/anellides.com\/es\/producto\/libro-lanna-y-los-secretos-de-los-peces-de-arena\/#itempage","url":"https:\/\/anellides.com\/es\/producto\/libro-lanna-y-los-secretos-de-los-peces-de-arena\/","name":"Libro L\u2019anna y los secretos de los peces de arena | Anellides","description":"Libro L'anna y los secretos de los peces de arena","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/anellides.com\/es\/#website"},"breadcrumb":{"@id":"https:\/\/anellides.com\/es\/producto\/libro-lanna-y-los-secretos-de-los-peces-de-arena\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/anellides.com\/wp-content\/files\/Llibre-Lanna-i-els-secrets-dels-peixos-de-sorra.jpg","@id":"https:\/\/anellides.com\/es\/producto\/libro-lanna-y-los-secretos-de-los-peces-de-arena\/#mainImage","width":900,"height":586,"caption":"Llibre L'anna i els secrets dels peixos de sorra"},"primaryImageOfPage":{"@id":"https:\/\/anellides.com\/es\/producto\/libro-lanna-y-los-secretos-de-los-peces-de-arena\/#mainImage"},"datePublished":"2025-01-10T08:30:23+00:00","dateModified":"2025-01-10T09:13:14+00:00"},{"@type":"Organization","@id":"https:\/\/anellides.com\/es\/#organization","name":"Anellides","description":"Serveis Ambientals Marins","url":"https:\/\/anellides.com\/es\/","sameAs":["https:\/\/www.instagram.com\/anellides\/","https:\/\/www.youtube.com\/channel\/UCY_NA_fh3v8B6uvCKdBLp4A"]},{"@type":"WebSite","@id":"https:\/\/anellides.com\/es\/#website","url":"https:\/\/anellides.com\/es\/","name":"Anellides","description":"Serveis Ambientals Marins","inLanguage":"es-ES","publisher":{"@id":"https:\/\/anellides.com\/es\/#organization"}}]}},"aioseo_meta_data":{"post_id":"18994","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"ItemPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2025-01-10 09:13:15","updated":"2025-06-04 12:47:58","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/anellides.com\/es\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/anellides.com\/es\/tienda\/\" title=\"Tienda\">Tienda<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/anellides.com\/es\/product-category\/llibres-es\/\" title=\"Llibres\">Llibres<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tLibro L\u2019anna y los secretos de los peces de arena\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/anellides.com\/es\/"},{"label":"Tienda","link":"https:\/\/anellides.com\/es\/tienda\/"},{"label":"Llibres","link":"https:\/\/anellides.com\/es\/product-category\/llibres-es\/"},{"label":"Libro L&#8217;anna y los secretos de los peces de arena","link":"https:\/\/anellides.com\/es\/producto\/libro-lanna-y-los-secretos-de-los-peces-de-arena\/"}],"_links":{"self":[{"href":"https:\/\/anellides.com\/es\/wp-json\/wp\/v2\/product\/18994","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/anellides.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/anellides.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/anellides.com\/es\/wp-json\/wp\/v2\/comments?post=18994"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/anellides.com\/es\/wp-json\/wp\/v2\/media\/18993"}],"wp:attachment":[{"href":"https:\/\/anellides.com\/es\/wp-json\/wp\/v2\/media?parent=18994"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/anellides.com\/es\/wp-json\/wp\/v2\/product_brand?post=18994"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/anellides.com\/es\/wp-json\/wp\/v2\/product_cat?post=18994"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/anellides.com\/es\/wp-json\/wp\/v2\/product_tag?post=18994"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}