{"id":11747,"date":"2023-05-22T09:28:54","date_gmt":"2023-05-22T09:28:54","guid":{"rendered":"https:\/\/anellides.com\/?post_type=tribe_events&#038;p=11747"},"modified":"2025-09-06T12:22:50","modified_gmt":"2025-09-06T12:22:50","slug":"snorkel-en-badalona-2025","status":"publish","type":"tribe_events","link":"https:\/\/anellides.com\/es\/event\/snorkel-en-badalona-2025\/","title":{"rendered":"Esn\u00f3rquels en Badalona 2025"},"content":{"rendered":"<p><img decoding=\"async\" class=\"alignnone wp-image-20156\" src=\"https:\/\/anellides.com\/wp-content\/files\/SLIDERS-WEB-4-1-e1754390952862.png\" alt=\"\" width=\"916\" height=\"229\" \/><\/p>\n<h3><strong>\u00a1Vuelven los esn\u00f3rquels en Badalona un verano m\u00e1s!<\/strong><\/h3>\n<p>Gracias a la colaboraci\u00f3n y apoyo del <a href=\"http:\/\/ajuntament.badalona.cat\/\">Ayuntamiento de Badalona<\/a>, \u200b\u200biniciamos una serie de salidas de esn\u00f3rquel para dar a conocer la biodiversidad marina de las playas del municipio. Una biodiversidad muy cercana, pero a la vez muy desconocida, que conocer\u00e1s a trav\u00e9s de estas sesiones, donde mostraremos la gran riqueza biol\u00f3gica de las playas urbanas. Adem\u00e1s, tambi\u00e9n aprender\u00e1s a utilizar el material de esn\u00f3rquel con seguridad.<\/p>\n<p>Todas las observaciones realizadas durante el esn\u00f3rquel servir\u00e1n para el proyecto de ciencia ciudadana <a href=\"https:\/\/anellides.com\/es\/blog\/portfolio-items\/posidonia-activa-3\/\">Posidonia Activa<\/a>, que tiene como objetivo cartografiar las praderas de <em>Posidonia oceanica<\/em> en zonas no protegidas, estudiar su biodiversidad e identificar \u00e1reas de alto valor ecol\u00f3gico para promover su conservaci\u00f3n.<\/p>\n<div class=\"fusion-button-wrapper\"><a class=\"fusion-button button-flat fusion-button-default-size button-default fusion-button-default button-1 fusion-button-default-span fusion-button-default-type\" target=\"_self\" href=\"https:\/\/forms.gle\/TZcnSizkGY3M5cJ26\"><span class=\"fusion-button-text awb-button__text awb-button__text--default\">\u00a1Inscr\u00edbete!<\/span><\/a><\/div>\n<h3><strong>Fechas:\u00a0 \u00a0GRUPOS COMPLETOS!<\/strong><\/h3>\n<h3>Septiembre<\/h3>\n<ul>\n<li>S\u00e1bado 13 de septiembre (17-19h)<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h3><strong>Punto de encuentro: <\/strong><\/h3>\n<p><a href=\"https:\/\/goo.gl\/maps\/i32qf2VZFc7kkx3RA\">Escuela del mar de Badalona<\/a><\/p>\n<h3><strong>Precio: <\/strong><\/h3>\n<p>Sesiones <strong>gratuitas\u00a0<\/strong><b>subvencionadas<\/b>\u00a0por el <a href=\"http:\/\/ajuntament.badalona.cat\/\">Ayuntamiento de Badalona<\/a>, con inscripci\u00f3n previa.<\/p>\n<p>&nbsp;<\/p>\n<h3 style=\"text-align: left;\"><strong>Observaciones:<\/strong><\/h3>\n<ul>\n<li style=\"text-align: left;\">Por cuestiones de seguridad, <strong>todos los asistentes tienen que saber nadar<\/strong>.<\/li>\n<li style=\"text-align: left;\"><strong>La edad m\u00ednima para participar en la actividad es de 8 a\u00f1os.<\/strong><\/li>\n<li style=\"text-align: left;\"><strong>Los menores tendr\u00e1n que estar acompa\u00f1ados por un adulto responsable<\/strong>, teniendo un m\u00ednimo de adulto por menor y un m\u00e1ximo de dos menores por adulto.<\/li>\n<li>Las plazas ser\u00e1n asignadas por orden de inscripci\u00f3n.<\/li>\n<li>Grupos de 20 participantes m\u00e1ximo.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>\u00a1Vuelven los esn\u00f3rquels en Badalona un verano m\u00e1s! Gracias a la colaboraci\u00f3n y apoyo del Ayuntamiento de Badalona, \u200b\u200biniciamos una serie de salidas de esn\u00f3rquel  [&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":18046,"template":"","meta":{"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[84,64,63,65],"class_list":["post-11747","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe_events_cat-adulto","tribe_events_cat-adultp","tribe_events_cat-familiar-es","tribe_events_cat-juvenil-es","cat_adulto","cat_adultp","cat_familiar-es","cat_juvenil-es"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"\u00a1Vuelven los esn\u00f3rquels en Badalona un verano m\u00e1s! Gracias a la colaboraci\u00f3n y apoyo del Ayuntamiento de Badalona, \u200b\u200biniciamos una serie de salidas de esn\u00f3rquel para dar a conocer la biodiversidad marina de las playas del municipio. Una biodiversidad muy cercana, pero a la vez muy desconocida, que conocer\u00e1s a trav\u00e9s de estas sesiones, donde\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Ane_admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"j5Te-Y3xjWrjCLJWsYSHtofnTHGBvK1IKvzlSorRXRc\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/anellides.com\/es\/event\/snorkel-en-badalona-2025\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/event\\\/snorkel-en-badalona-2025\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/anellides.com\\\/es\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/events\\\/#listItem\",\"name\":\"Eventos\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/events\\\/#listItem\",\"position\":2,\"name\":\"Eventos\",\"item\":\"https:\\\/\\\/anellides.com\\\/es\\\/events\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/events\\\/category\\\/familiar-es\\\/#listItem\",\"name\":\"Familiar\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/events\\\/category\\\/familiar-es\\\/#listItem\",\"position\":3,\"name\":\"Familiar\",\"item\":\"https:\\\/\\\/anellides.com\\\/es\\\/events\\\/category\\\/familiar-es\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/event\\\/snorkel-en-badalona-2025\\\/#listItem\",\"name\":\"Esn\\u00f3rquels en Badalona 2025\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/events\\\/#listItem\",\"name\":\"Eventos\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/event\\\/snorkel-en-badalona-2025\\\/#listItem\",\"position\":4,\"name\":\"Esn\\u00f3rquels en Badalona 2025\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/events\\\/category\\\/familiar-es\\\/#listItem\",\"name\":\"Familiar\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/#organization\",\"name\":\"Anellides\",\"description\":\"Serveis Ambientals Marins\",\"url\":\"https:\\\/\\\/anellides.com\\\/es\\\/\",\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/anellides\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCY_NA_fh3v8B6uvCKdBLp4A\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/blog\\\/author\\\/ane_admin\\\/#author\",\"url\":\"https:\\\/\\\/anellides.com\\\/es\\\/blog\\\/author\\\/ane_admin\\\/\",\"name\":\"Ane_admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/event\\\/snorkel-en-badalona-2025\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/128ddaa8fd25bf4339cb192ade2a01e84e20a555b66442ee33957ea7b9aaca15?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Ane_admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/event\\\/snorkel-en-badalona-2025\\\/#webpage\",\"url\":\"https:\\\/\\\/anellides.com\\\/es\\\/event\\\/snorkel-en-badalona-2025\\\/\",\"name\":\"Esn\\u00f3rquels en Badalona 2025 | Anellides\",\"description\":\"\\u00a1Vuelven los esn\\u00f3rquels en Badalona un verano m\\u00e1s! Gracias a la colaboraci\\u00f3n y apoyo del Ayuntamiento de Badalona, \\u200b\\u200biniciamos una serie de salidas de esn\\u00f3rquel para dar a conocer la biodiversidad marina de las playas del municipio. Una biodiversidad muy cercana, pero a la vez muy desconocida, que conocer\\u00e1s a trav\\u00e9s de estas sesiones, donde\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/event\\\/snorkel-en-badalona-2025\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/blog\\\/author\\\/ane_admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/blog\\\/author\\\/ane_admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/anellides.com\\\/wp-content\\\/files\\\/BADALONA-2.png\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/event\\\/snorkel-en-badalona-2025\\\/#mainImage\",\"width\":1920,\"height\":1080},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/event\\\/snorkel-en-badalona-2025\\\/#mainImage\"},\"datePublished\":\"2023-05-22T09:28:54+00:00\",\"dateModified\":\"2025-09-06T12:22:50+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/anellides.com\\\/es\\\/\",\"name\":\"Anellides\",\"description\":\"Serveis Ambientals Marins\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/anellides.com\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Esn\u00f3rquels en Badalona 2025 | Anellides","description":"\u00a1Vuelven los esn\u00f3rquels en Badalona un verano m\u00e1s! Gracias a la colaboraci\u00f3n y apoyo del Ayuntamiento de Badalona, \u200b\u200biniciamos una serie de salidas de esn\u00f3rquel para dar a conocer la biodiversidad marina de las playas del municipio. Una biodiversidad muy cercana, pero a la vez muy desconocida, que conocer\u00e1s a trav\u00e9s de estas sesiones, donde","canonical_url":"https:\/\/anellides.com\/es\/event\/snorkel-en-badalona-2025\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"j5Te-Y3xjWrjCLJWsYSHtofnTHGBvK1IKvzlSorRXRc","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/anellides.com\/es\/event\/snorkel-en-badalona-2025\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/anellides.com\/es\/#listItem","position":1,"name":"Home","item":"https:\/\/anellides.com\/es\/","nextItem":{"@type":"ListItem","@id":"https:\/\/anellides.com\/es\/events\/#listItem","name":"Eventos"}},{"@type":"ListItem","@id":"https:\/\/anellides.com\/es\/events\/#listItem","position":2,"name":"Eventos","item":"https:\/\/anellides.com\/es\/events\/","nextItem":{"@type":"ListItem","@id":"https:\/\/anellides.com\/es\/events\/category\/familiar-es\/#listItem","name":"Familiar"},"previousItem":{"@type":"ListItem","@id":"https:\/\/anellides.com\/es\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/anellides.com\/es\/events\/category\/familiar-es\/#listItem","position":3,"name":"Familiar","item":"https:\/\/anellides.com\/es\/events\/category\/familiar-es\/","nextItem":{"@type":"ListItem","@id":"https:\/\/anellides.com\/es\/event\/snorkel-en-badalona-2025\/#listItem","name":"Esn\u00f3rquels en Badalona 2025"},"previousItem":{"@type":"ListItem","@id":"https:\/\/anellides.com\/es\/events\/#listItem","name":"Eventos"}},{"@type":"ListItem","@id":"https:\/\/anellides.com\/es\/event\/snorkel-en-badalona-2025\/#listItem","position":4,"name":"Esn\u00f3rquels en Badalona 2025","previousItem":{"@type":"ListItem","@id":"https:\/\/anellides.com\/es\/events\/category\/familiar-es\/#listItem","name":"Familiar"}}]},{"@type":"Organization","@id":"https:\/\/anellides.com\/es\/#organization","name":"Anellides","description":"Serveis Ambientals Marins","url":"https:\/\/anellides.com\/es\/","sameAs":["https:\/\/www.instagram.com\/anellides\/","https:\/\/www.youtube.com\/channel\/UCY_NA_fh3v8B6uvCKdBLp4A"]},{"@type":"Person","@id":"https:\/\/anellides.com\/es\/blog\/author\/ane_admin\/#author","url":"https:\/\/anellides.com\/es\/blog\/author\/ane_admin\/","name":"Ane_admin","image":{"@type":"ImageObject","@id":"https:\/\/anellides.com\/es\/event\/snorkel-en-badalona-2025\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/128ddaa8fd25bf4339cb192ade2a01e84e20a555b66442ee33957ea7b9aaca15?s=96&d=mm&r=g","width":96,"height":96,"caption":"Ane_admin"}},{"@type":"WebPage","@id":"https:\/\/anellides.com\/es\/event\/snorkel-en-badalona-2025\/#webpage","url":"https:\/\/anellides.com\/es\/event\/snorkel-en-badalona-2025\/","name":"Esn\u00f3rquels en Badalona 2025 | Anellides","description":"\u00a1Vuelven los esn\u00f3rquels en Badalona un verano m\u00e1s! Gracias a la colaboraci\u00f3n y apoyo del Ayuntamiento de Badalona, \u200b\u200biniciamos una serie de salidas de esn\u00f3rquel para dar a conocer la biodiversidad marina de las playas del municipio. Una biodiversidad muy cercana, pero a la vez muy desconocida, que conocer\u00e1s a trav\u00e9s de estas sesiones, donde","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/anellides.com\/es\/#website"},"breadcrumb":{"@id":"https:\/\/anellides.com\/es\/event\/snorkel-en-badalona-2025\/#breadcrumblist"},"author":{"@id":"https:\/\/anellides.com\/es\/blog\/author\/ane_admin\/#author"},"creator":{"@id":"https:\/\/anellides.com\/es\/blog\/author\/ane_admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/anellides.com\/wp-content\/files\/BADALONA-2.png","@id":"https:\/\/anellides.com\/es\/event\/snorkel-en-badalona-2025\/#mainImage","width":1920,"height":1080},"primaryImageOfPage":{"@id":"https:\/\/anellides.com\/es\/event\/snorkel-en-badalona-2025\/#mainImage"},"datePublished":"2023-05-22T09:28:54+00:00","dateModified":"2025-09-06T12:22:50+00:00"},{"@type":"WebSite","@id":"https:\/\/anellides.com\/es\/#website","url":"https:\/\/anellides.com\/es\/","name":"Anellides","description":"Serveis Ambientals Marins","inLanguage":"es-ES","publisher":{"@id":"https:\/\/anellides.com\/es\/#organization"}}]}},"aioseo_meta_data":{"post_id":"11747","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2023-05-22 09:21:15","updated":"2025-09-06 12:23:28","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/anellides.com\/es\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/anellides.com\/es\/events\/\" title=\"Eventos\">Eventos<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/anellides.com\/es\/events\/category\/familiar-es\/\" title=\"Familiar\">Familiar<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tEsn\u00f3rquels en Badalona 2025\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/anellides.com\/es\/"},{"label":"Eventos","link":"https:\/\/anellides.com\/es\/events\/"},{"label":"Familiar","link":"https:\/\/anellides.com\/es\/events\/category\/familiar-es\/"},{"label":"Esn\u00f3rquels en Badalona 2025","link":"https:\/\/anellides.com\/es\/event\/snorkel-en-badalona-2025\/"}],"_links":{"self":[{"href":"https:\/\/anellides.com\/es\/wp-json\/wp\/v2\/tribe_events\/11747","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/anellides.com\/es\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/anellides.com\/es\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/anellides.com\/es\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":38,"href":"https:\/\/anellides.com\/es\/wp-json\/wp\/v2\/tribe_events\/11747\/revisions"}],"predecessor-version":[{"id":20414,"href":"https:\/\/anellides.com\/es\/wp-json\/wp\/v2\/tribe_events\/11747\/revisions\/20414"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/anellides.com\/es\/wp-json\/wp\/v2\/media\/18046"}],"wp:attachment":[{"href":"https:\/\/anellides.com\/es\/wp-json\/wp\/v2\/media?parent=11747"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/anellides.com\/es\/wp-json\/wp\/v2\/tags?post=11747"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/anellides.com\/es\/wp-json\/wp\/v2\/tribe_events_cat?post=11747"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}